{"id":3440,"date":"2021-03-19T08:44:34","date_gmt":"2021-03-19T07:44:34","guid":{"rendered":"https:\/\/www.dos30.com\/actualidad\/?p=3440"},"modified":"2022-02-02T15:34:22","modified_gmt":"2022-02-02T14:34:22","slug":"audiencias-18-marzo-2021","status":"publish","type":"post","link":"https:\/\/www.dos30.com\/actualidad\/2021\/03\/19\/audiencias-18-marzo-2021\/","title":{"rendered":"AUDIENCIAS 18 MARZO 2021"},"content":{"rendered":"<p><strong>Telecinco (17.8%) lidera el d\u00eda con los grandes datos de La Isla de las Tentaciones (26.4%)<\/strong><\/p>\n<p><a href=\"https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2021\/03\/1-8.png\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-3441\" src=\"https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2021\/03\/1-8-300x169.png\" alt=\"\" width=\"609\" height=\"343\" srcset=\"https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2021\/03\/1-8-300x169.png 300w, https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2021\/03\/1-8-768x434.png 768w, https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2021\/03\/1-8.png 937w\" sizes=\"auto, (max-width: 609px) 100vw, 609px\" \/><\/a><\/p>\n<p><strong><span class=\"r-18u37iz\">La Isla De Las Tentaciones<\/span><\/strong><span class=\"css-901oao css-16my406 r-poiln3 r-bcqeeo r-qvutc0\"><strong>\u00a0<\/strong>lidera con 18.8 puntos de diferencia en su franja de emisi\u00f3n con un excelente 26.4% de cuota, 3.166.000 espectadores y 61.1% de fidelidad. Sube al 32.1% de cuota comercialmente hablando.<\/span><\/p>\n<p><strong><span class=\"r-18u37iz\">Cu\u00e9ntame c\u00f3mo pas\u00f3<\/span><\/strong><span class=\"css-901oao css-16my406 r-poiln3 r-bcqeeo r-qvutc0\">\u00a0contin\u00faa como la ficci\u00f3n nacional m\u00e1s vista al seducir al 10.3% de cuota, 1.747.000 espectadores y 46.7% de fidelidad. Mejora en un 19.3% la cuota de La 1\u00a0<\/span>en el d\u00eda. Adem\u00e1s, suma 116.000 espectadores m\u00e1s en diferido.<\/p>\n<p><strong><span class=\"r-18u37iz\">Pasapalabra<\/span><\/strong><span class=\"css-901oao css-16my406 r-poiln3 r-bcqeeo r-qvutc0\">\u00a0vuela como lo m\u00e1s visto del d\u00eda con un 25.3% de cuota, 3.577.000 espectadores y 5.960.000 contactos. Mejora en un 81% la cuota de Antena 3.<\/span><\/p>\n<p><span class=\"css-901oao css-16my406 r-poiln3 r-bcqeeo r-qvutc0\">El pen\u00faltimo cap\u00edtulo de <\/span><strong><span class=\"r-18u37iz\">El Nudo<\/span><\/strong><span class=\"css-901oao css-16my406 r-poiln3 r-bcqeeo r-qvutc0\">\u00a0en el prime time de Antena 3\u00a0<\/span><span class=\"css-901oao css-16my406 r-poiln3 r-bcqeeo r-qvutc0\">consigue su mejor dato desde el 25 de <\/span><span class=\"r-18u37iz\">febrero<\/span><span class=\"css-901oao css-16my406 r-poiln3 r-bcqeeo r-qvutc0\">\u00a0al promediar un 7.8% de cuota y 976.000 espectadores. Su media de edad 58 a\u00f1os.<\/span><\/p>\n<p><span class=\"css-901oao css-16my406 r-poiln3 r-bcqeeo r-qvutc0\">M\u00e1ximo hist\u00f3rico\u00a0para <strong>El condensador de Fluzo<\/strong><\/span><span class=\"css-901oao css-16my406 r-poiln3 r-bcqeeo r-qvutc0\">\u00a0en el prime time de La 2\u00a0<\/span><span class=\"css-901oao css-16my406 r-poiln3 r-bcqeeo r-qvutc0\">seduciendo al 3.4% de cuota, 607.000 espectadores y 30.1% de fidelidad. Enormes datos semana a semana para\u00a0<\/span><span class=\"r-18u37iz\">el programa.<\/span><\/p>\n<p><a href=\"https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2021\/03\/4-10.png\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-3444\" src=\"https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2021\/03\/4-10-300x85.png\" alt=\"\" width=\"600\" height=\"170\" srcset=\"https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2021\/03\/4-10-300x85.png 300w, https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2021\/03\/4-10.png 724w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/a><\/p>\n<p><a href=\"https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2021\/03\/5-9.png\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-3445\" src=\"https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2021\/03\/5-9-300x84.png\" alt=\"\" width=\"604\" height=\"169\" srcset=\"https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2021\/03\/5-9-300x84.png 300w, https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2021\/03\/5-9-768x214.png 768w, https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2021\/03\/5-9.png 854w\" sizes=\"auto, (max-width: 604px) 100vw, 604px\" \/><\/a><\/p>\n<p><a href=\"https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2021\/03\/2-10.png\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-3442\" src=\"https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2021\/03\/2-10-300x176.png\" alt=\"\" width=\"605\" height=\"355\" srcset=\"https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2021\/03\/2-10-300x176.png 300w, https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2021\/03\/2-10-768x451.png 768w, https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2021\/03\/2-10.png 900w\" sizes=\"auto, (max-width: 605px) 100vw, 605px\" \/><\/a><\/p>\n<p><span class=\"css-901oao css-16my406 r-poiln3 r-bcqeeo r-qvutc0\">Incre\u00edble\u00a0prime time de TV3\u00a0<\/span><span class=\"css-901oao css-16my406 r-poiln3 r-bcqeeo r-qvutc0\">en la noche de ayer.\u00a0<\/span><strong><span class=\"r-18u37iz\">Pol\u00f2nia<\/span><\/strong><span class=\"css-901oao css-16my406 r-poiln3 r-bcqeeo r-qvutc0\"><strong>\u00a0<\/strong>marca\u00a0m\u00e1ximo anual\u00a0y lidera su franja con un 24.3% y 674.000 espectadores.\u00a0<\/span><strong><span class=\"r-18u37iz\">APM?<\/span><\/strong><span class=\"css-901oao css-16my406 r-poiln3 r-bcqeeo r-qvutc0\">\u00a0tambi\u00e9n marca m\u00e1ximo con un 15.3% y 341.000 espectadores.<\/span><\/p>\n<p><span class=\"css-901oao css-16my406 r-poiln3 r-bcqeeo r-qvutc0\">Segundo\u00a0mejor dato hist\u00f3rico para el concurso <strong>Esto no es normal\u00a0<\/strong><\/span><span class=\"css-901oao css-16my406 r-poiln3 r-bcqeeo r-qvutc0\">en la tarde de ETB2\u00a0<\/span><span class=\"css-901oao css-16my406 r-poiln3 r-bcqeeo r-qvutc0\">conquistando al 12.5% de cuota, 62.000 espectadores y 60.2% de fidelidad.<\/span><\/p>\n<p><strong><span class=\"css-901oao css-16my406 r-poiln3 r-bcqeeo r-qvutc0\">Land Rober: Tunai Show<\/span><\/strong><span class=\"css-901oao css-16my406 r-poiln3 r-bcqeeo r-qvutc0\">\u00a0firma un 16.7% de cuota, 127.000 espectadores y\u00a0es visto en alg\u00fan momento por 261.000 espectadores. M<\/span><span class=\"css-901oao css-16my406 r-poiln3 r-bcqeeo r-qvutc0\">antienen al 48.8% de todos los espectadores durante los 98 minutos del programa.<\/span><\/p>\n<p><span class=\"css-901oao css-16my406 r-poiln3 r-bcqeeo r-qvutc0\">Gran estreno de la Temporada 2 de <\/span><strong><span class=\"r-18u37iz\">Trotacampos<\/span><\/strong><span class=\"css-901oao css-16my406 r-poiln3 r-bcqeeo r-qvutc0\"> en la noche de CMM\u00a0<\/span>qued\u00e1ndose con el 6.1% de cuota, 45.000 espectadores y llegando a los 114.000 contactos.<\/p>\n<p><span class=\"css-901oao css-16my406 r-poiln3 r-bcqeeo r-qvutc0\">Fant\u00e1stico trabajo de La7TV\u00a0<\/span><span class=\"css-901oao css-16my406 r-poiln3 r-bcqeeo r-qvutc0\">con <\/span><strong><span class=\"r-18u37iz\">Especial Moci\u00f3n Censura<\/span><\/strong><span class=\"css-901oao css-16my406 r-poiln3 r-bcqeeo r-qvutc0\"> mejorando en el d\u00eda\u00a0<\/span>al firmar un 5.6% de cuota. En total 285.000 personas se asoman durante el d\u00eda por el canal.<\/p>\n<p><a href=\"https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2021\/03\/3-10.png\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-3443\" src=\"https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2021\/03\/3-10-300x178.png\" alt=\"\" width=\"580\" height=\"344\" srcset=\"https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2021\/03\/3-10-300x178.png 300w, https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2021\/03\/3-10-768x455.png 768w, https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2021\/03\/3-10.png 892w\" sizes=\"auto, (max-width: 580px) 100vw, 580px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Telecinco (17.8%) lidera el d\u00eda con los grandes datos de La Isla de las Tentaciones (26.4%) La Isla De Las Tentaciones\u00a0lidera con 18.8 puntos de diferencia en su franja de emisi\u00f3n con un excelente 26.4% de cuota, 3.166.000 espectadores y 61.1% de fidelidad. Sube al 32.1% de cuota comercialmente hablando. Cu\u00e9ntame c\u00f3mo pas\u00f3\u00a0contin\u00faa como la &hellip; <a href=\"https:\/\/www.dos30.com\/actualidad\/2021\/03\/19\/audiencias-18-marzo-2021\/\" class=\"more-link\">Sigue leyendo <span class=\"screen-reader-text\">AUDIENCIAS 18 MARZO 2021<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[24],"tags":[],"class_list":["post-3440","post","type-post","status-publish","format-standard","hentry","category-audiencias-diarias"],"_links":{"self":[{"href":"https:\/\/www.dos30.com\/actualidad\/wp-json\/wp\/v2\/posts\/3440","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dos30.com\/actualidad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dos30.com\/actualidad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.dos30.com\/actualidad\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dos30.com\/actualidad\/wp-json\/wp\/v2\/comments?post=3440"}],"version-history":[{"count":4,"href":"https:\/\/www.dos30.com\/actualidad\/wp-json\/wp\/v2\/posts\/3440\/revisions"}],"predecessor-version":[{"id":3450,"href":"https:\/\/www.dos30.com\/actualidad\/wp-json\/wp\/v2\/posts\/3440\/revisions\/3450"}],"wp:attachment":[{"href":"https:\/\/www.dos30.com\/actualidad\/wp-json\/wp\/v2\/media?parent=3440"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dos30.com\/actualidad\/wp-json\/wp\/v2\/categories?post=3440"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dos30.com\/actualidad\/wp-json\/wp\/v2\/tags?post=3440"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}