{"id":3482,"date":"2021-03-23T08:55:30","date_gmt":"2021-03-23T07:55:30","guid":{"rendered":"https:\/\/www.dos30.com\/actualidad\/?p=3482"},"modified":"2022-02-02T15:34:22","modified_gmt":"2022-02-02T14:34:22","slug":"audiencias-22-marzo-2021","status":"publish","type":"post","link":"https:\/\/www.dos30.com\/actualidad\/2021\/03\/23\/audiencias-22-marzo-2021\/","title":{"rendered":"AUDIENCIAS 22 MARZO 2021"},"content":{"rendered":"<p><strong>Antena 3\u00a0copa el ranking de las emisiones m\u00e1s vistas del d\u00eda pero Telecinco se lleva el liderazgo con un 17.8%<\/strong><\/p>\n<p><a href=\"https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2021\/03\/1-10.png\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-3476\" src=\"https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2021\/03\/1-10-300x165.png\" alt=\"\" width=\"602\" height=\"331\" srcset=\"https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2021\/03\/1-10-300x165.png 300w, https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2021\/03\/1-10-768x423.png 768w, https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2021\/03\/1-10.png 934w\" sizes=\"auto, (max-width: 602px) 100vw, 602px\" \/><\/a><\/p>\n<p><span class=\"css-901oao css-16my406 r-poiln3 r-bcqeeo r-qvutc0\"><strong>Antena 3 Noticias 2\u00a0<\/strong>es lo m\u00e1s visto del d\u00eda con un 22.2% de cuota, 3.741.000 espectadores y 6.062.000 contactos. Gusta al promediar un 61.7% de fidelidad.<\/span><\/p>\n<p><span class=\"css-901oao css-16my406 r-poiln3 r-bcqeeo r-qvutc0\">R\u00e9cord de temporada\u00a0en share para <\/span><strong><span class=\"r-18u37iz\">Maestros De La Costura<\/span><\/strong><span class=\"css-901oao css-16my406 r-poiln3 r-bcqeeo r-qvutc0\"> al alcanzar ayer un sensacional 12.1% de cuota en La 1. El programa\u00a0<\/span>fue seguido por 1.335.000 espectadores y mejora un +12% el dato logrado la semana pasada.<\/p>\n<p><strong><span class=\"r-18u37iz\">Caronte<\/span><\/strong><span class=\"css-901oao css-16my406 r-poiln3 r-bcqeeo r-qvutc0\">\u00a0se hizo anoche con el 6.3% de la audiencia en el prime time de Cuatro<\/span><span class=\"css-901oao css-16my406 r-poiln3 r-bcqeeo r-qvutc0\">, dato que supone una mejora del +32.9% respecto al resultado de la cadena en el d\u00eda. 822.000 espectadores siguieron anoche el nuevo cap\u00edtulo.<\/span><\/p>\n<p><strong><span class=\"r-18u37iz\">Mujer<\/span><\/strong><span class=\"css-901oao css-16my406 r-poiln3 r-bcqeeo r-qvutc0\"><strong>\u00a0<\/strong>es\u00a0l\u00edder s\u00f3lido en su franja de emisi\u00f3n con un 16.8% de cuota, 2.178.000 espectadores y\u00a0m\u00e1s de 4 millones de contactos. 11.1% de plusval\u00eda con el canal en el d\u00eda.<\/span><\/p>\n<p><strong><span class=\"r-18u37iz\">El debate de las tentaciones<\/span><\/strong><span class=\"css-901oao css-16my406 r-poiln3 r-bcqeeo r-qvutc0\">\u00a0firm\u00f3 ayer un 15% de share en el\u00a0prime time de Telecinco\u00a0<\/span>y fue seguido por 1.392.000 espectadores. El debate presentado por Sandra Barneda super\u00f3 los 4.4 millones de contactos y aporta casi el 13% al dato de la cadena en el d\u00eda.<\/p>\n<p><strong><span class=\"r-18u37iz\">El Programa De Ana Rosa<\/span><\/strong><span class=\"css-901oao css-16my406 r-poiln3 r-bcqeeo r-qvutc0\"> logra su\u00a0mejor dato en share de los \u00faltimos 2 a\u00f1os analizados al firmar un 25.2% de share.<\/span><\/p>\n<p><a href=\"https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2021\/03\/4-12.png\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-3479\" src=\"https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2021\/03\/4-12-300x85.png\" alt=\"\" width=\"593\" height=\"168\" srcset=\"https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2021\/03\/4-12-300x85.png 300w, https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2021\/03\/4-12.png 724w\" sizes=\"auto, (max-width: 593px) 100vw, 593px\" \/><\/a><\/p>\n<p><a href=\"https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2021\/03\/5-11.png\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-3480\" src=\"https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2021\/03\/5-11-300x84.png\" alt=\"\" width=\"596\" height=\"167\" srcset=\"https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2021\/03\/5-11-300x84.png 300w, https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2021\/03\/5-11-768x214.png 768w, https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2021\/03\/5-11.png 854w\" sizes=\"auto, (max-width: 596px) 100vw, 596px\" \/><\/a><\/p>\n<p><a href=\"https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2021\/03\/2-12.png\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-3477\" src=\"https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2021\/03\/2-12-300x176.png\" alt=\"\" width=\"598\" height=\"351\" srcset=\"https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2021\/03\/2-12-300x176.png 300w, https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2021\/03\/2-12-768x451.png 768w, https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2021\/03\/2-12.png 900w\" sizes=\"auto, (max-width: 598px) 100vw, 598px\" \/><\/a><\/p>\n<p><span class=\"r-18u37iz\"><strong>Crims<\/strong>\u00a0en TV3<\/span><span class=\"css-901oao css-16my406 r-poiln3 r-bcqeeo r-qvutc0\"> mejora 2 puntos su resultado de la semana pasada y lidera su franja de emisi\u00f3n, con m\u00e1s de 5 puntos de diferencia, al firmar un 17.5% de cuota y 458.000 espectadores.<\/span><\/p>\n<p>El conquistador del Caribe\u00a0<span class=\"css-901oao css-16my406 r-poiln3 r-bcqeeo r-qvutc0\">en el prime de <strong>ETB2\u00a0<\/strong><\/span><span class=\"css-901oao css-16my406 r-poiln3 r-bcqeeo r-qvutc0\">arrasa como siempre con un 24.7% de cuota, 130.000 espectadores y 56.1% de fidelidad.\u00a0<\/span><span class=\"r-18u37iz\">El programa\u00a0<\/span><span class=\"css-901oao css-16my406 r-poiln3 r-bcqeeo r-qvutc0\">aporta un tercio de la audiencia del canal en el d\u00eda.<\/span><\/p>\n<p><span class=\"css-901oao css-16my406 r-poiln3 r-bcqeeo r-qvutc0\">Enorme 13.8% de cuota y 34.000 espectadores para el programa\u00a0<strong>En Jake<\/strong> en la ma\u00f1ana de ETB2.\u00a0<\/span>En sus 2 horas de duraci\u00f3n fideliza al 35.6% de la audiencia.<\/p>\n<p><strong><span class=\"r-18u37iz\">Mi c\u00e1mara y yo<\/span><\/strong><span class=\"css-901oao css-16my406 r-poiln3 r-bcqeeo r-qvutc0\"><strong>\u00a0<\/strong>consigue ser el espacio no informativo + visto de Telemadrid\u00a0<\/span>al firmar un 5.1% de cuota, 107.000 espectadores y 41% de fidelidad. La media de edad del programa es de<span class=\"css-901oao css-16my406 r-poiln3 r-bcqeeo r-qvutc0\">\u00a058 a\u00f1os.<\/span><\/p>\n<p><span class=\"r-18u37iz\"><strong>Terra Viva<\/strong> en \u00c0 Punt<\/span><span class=\"css-901oao css-16my406 r-poiln3 r-bcqeeo r-qvutc0\"> dobla la media del canal\u00a0<\/span>al hacerse con el 7% de cuota, 47.000 espectadores y 33.6% de fidelidad.<\/p>\n<p><a href=\"https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2021\/03\/3-12.png\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-3478\" src=\"https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2021\/03\/3-12-300x170.png\" alt=\"\" width=\"574\" height=\"325\" srcset=\"https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2021\/03\/3-12-300x170.png 300w, https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2021\/03\/3-12-768x435.png 768w, https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2021\/03\/3-12.png 892w\" sizes=\"auto, (max-width: 574px) 100vw, 574px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Antena 3\u00a0copa el ranking de las emisiones m\u00e1s vistas del d\u00eda pero Telecinco se lleva el liderazgo con un 17.8% Antena 3 Noticias 2\u00a0es lo m\u00e1s visto del d\u00eda con un 22.2% de cuota, 3.741.000 espectadores y 6.062.000 contactos. Gusta al promediar un 61.7% de fidelidad. R\u00e9cord de temporada\u00a0en share para Maestros De La Costura &hellip; <a href=\"https:\/\/www.dos30.com\/actualidad\/2021\/03\/23\/audiencias-22-marzo-2021\/\" class=\"more-link\">Sigue leyendo <span class=\"screen-reader-text\">AUDIENCIAS 22 MARZO 2021<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":3483,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[24],"tags":[],"class_list":["post-3482","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-audiencias-diarias"],"_links":{"self":[{"href":"https:\/\/www.dos30.com\/actualidad\/wp-json\/wp\/v2\/posts\/3482","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dos30.com\/actualidad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dos30.com\/actualidad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.dos30.com\/actualidad\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dos30.com\/actualidad\/wp-json\/wp\/v2\/comments?post=3482"}],"version-history":[{"count":2,"href":"https:\/\/www.dos30.com\/actualidad\/wp-json\/wp\/v2\/posts\/3482\/revisions"}],"predecessor-version":[{"id":3485,"href":"https:\/\/www.dos30.com\/actualidad\/wp-json\/wp\/v2\/posts\/3482\/revisions\/3485"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.dos30.com\/actualidad\/wp-json\/wp\/v2\/media\/3483"}],"wp:attachment":[{"href":"https:\/\/www.dos30.com\/actualidad\/wp-json\/wp\/v2\/media?parent=3482"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dos30.com\/actualidad\/wp-json\/wp\/v2\/categories?post=3482"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dos30.com\/actualidad\/wp-json\/wp\/v2\/tags?post=3482"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}