{"id":6788,"date":"2022-02-05T11:09:21","date_gmt":"2022-02-05T10:09:21","guid":{"rendered":"https:\/\/www.dos30.com\/actualidad\/?p=6788"},"modified":"2022-02-05T11:09:22","modified_gmt":"2022-02-05T10:09:22","slug":"audiencias-04-febrero-2022","status":"publish","type":"post","link":"https:\/\/www.dos30.com\/actualidad\/2022\/02\/05\/audiencias-04-febrero-2022\/","title":{"rendered":"AUDIENCIAS 04 FEBRERO 2022"},"content":{"rendered":"\n<p><strong>&#8216;Montealto&#8217; y &#8216;Tu cara me suena&#8217; protagonizan el duelo por las audiencias del viernes noche.<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2022\/02\/NACIONAL.jpg\" alt=\"\" class=\"wp-image-6790\" width=\"836\" height=\"431\" srcset=\"https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2022\/02\/NACIONAL.jpg 746w, https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2022\/02\/NACIONAL-300x155.jpg 300w\" sizes=\"auto, (max-width: 836px) 100vw, 836px\" \/><\/figure>\n\n\n\n<p><strong>MONTEALTO<\/strong> se marc\u00f3 anoche un 14% de share en el Prime Time de Telecinco y congreg\u00f3 a un total de 1.345.000 espectadores. El programa super\u00f3 los 5.6 millones de contactos y aporta m\u00e1s de 1\/4 al dato diario de Telecinco.<\/p>\n\n\n\n<p>Enormes los datos de <strong>TU CARA ME SUENA<\/strong> al registrar anoche un 21% de share en Antena 3. El programa super\u00f3 los 2.4 millones de espectadores, roz\u00f3 el 40% de fidelidad y lidera en su franja de emisi\u00f3n.<\/p>\n\n\n\n<p>4.1% de share para <strong>LAS CLAVES DEL S.XXI <\/strong>en pleno Prime Time del viernes de La1. El programa con Javier Ruiz reuni\u00f3 anoche a 533.000 espectadores y lleg\u00f3 a los 3.8 millones de contactos. 11.3% de aportaci\u00f3n al canal en el d\u00eda.<\/p>\n\n\n\n<p>458.000 espectadores siguieron anoche el reportaje de <strong>EN EL PUNTO DE MIRA<\/strong> en el prime time de Cuatro, dato que se traduce en el 3.5% de share. El programa lleg\u00f3 a superar los 2.4 millones de contactos y aporta m\u00e1s del 8% a la cadena.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2022\/02\/MINUTO-DE-ORO.jpg\" alt=\"\" class=\"wp-image-6791\" width=\"838\" height=\"218\" srcset=\"https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2022\/02\/MINUTO-DE-ORO.jpg 791w, https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2022\/02\/MINUTO-DE-ORO-300x78.jpg 300w, https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2022\/02\/MINUTO-DE-ORO-768x200.jpg 768w\" sizes=\"auto, (max-width: 838px) 100vw, 838px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"976\" height=\"238\" src=\"https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2022\/02\/SPOT-ORO.jpg\" alt=\"\" class=\"wp-image-6792\" srcset=\"https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2022\/02\/SPOT-ORO.jpg 976w, https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2022\/02\/SPOT-ORO-300x73.jpg 300w, https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2022\/02\/SPOT-ORO-768x187.jpg 768w\" sizes=\"auto, (max-width: 976px) 100vw, 976px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2022\/02\/FORTA.jpg\" alt=\"\" class=\"wp-image-6793\" width=\"842\" height=\"466\" srcset=\"https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2022\/02\/FORTA.jpg 694w, https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2022\/02\/FORTA-300x166.jpg 300w\" sizes=\"auto, (max-width: 842px) 100vw, 842px\" \/><\/figure>\n\n\n\n<p>Muy contentos con los datos de <strong>TAP ZAPING<\/strong> en el prime time del viernes de \u00c0 Punt al registrar ayer un 2.5% de share y congregar a 42.000 espectadores. 137.000 contactos acumulados y 31% de fidelidad.<\/p>\n\n\n\n<p>Sonsoles Artigas aterriz\u00f3 anoche en <strong>AQU\u00cd LA TELE <\/strong>y lo hizo por todo lo alto. El programa de TVCAN firm\u00f3 un sobresaliente 7.3% de share, 42.000 espectadores, 46% de fidelidad y supera la media de la cadena en un +40.8%.<\/p>\n\n\n\n<p>Grand\u00edsimos los datos que consigue d\u00eda tras d\u00eda el magazine <strong>QU\u00c9DATE CONMIGO<\/strong> en la ma\u00f1ana de LA7TV. Ojo al dato: 21.4% de share, 21.000 espectadores, 43.8% de fidelidad y programa de mayor aportaci\u00f3n al canal.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2022\/02\/PAGO.jpg\" alt=\"\" class=\"wp-image-6794\" width=\"839\" height=\"465\" srcset=\"https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2022\/02\/PAGO.jpg 693w, https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2022\/02\/PAGO-300x166.jpg 300w\" sizes=\"auto, (max-width: 839px) 100vw, 839px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>&#8216;Montealto&#8217; y &#8216;Tu cara me suena&#8217; protagonizan el duelo por las audiencias del viernes noche. MONTEALTO se marc\u00f3 anoche un 14% de share en el Prime Time de Telecinco y congreg\u00f3 a un total de 1.345.000 espectadores. El programa super\u00f3 los 5.6 millones de contactos y aporta m\u00e1s de 1\/4 al dato diario de Telecinco. &hellip; <a href=\"https:\/\/www.dos30.com\/actualidad\/2022\/02\/05\/audiencias-04-febrero-2022\/\" class=\"more-link\">Sigue leyendo <span class=\"screen-reader-text\">AUDIENCIAS 04 FEBRERO 2022<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[24],"tags":[],"class_list":["post-6788","post","type-post","status-publish","format-standard","hentry","category-audiencias-diarias"],"_links":{"self":[{"href":"https:\/\/www.dos30.com\/actualidad\/wp-json\/wp\/v2\/posts\/6788","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dos30.com\/actualidad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dos30.com\/actualidad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.dos30.com\/actualidad\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dos30.com\/actualidad\/wp-json\/wp\/v2\/comments?post=6788"}],"version-history":[{"count":1,"href":"https:\/\/www.dos30.com\/actualidad\/wp-json\/wp\/v2\/posts\/6788\/revisions"}],"predecessor-version":[{"id":6795,"href":"https:\/\/www.dos30.com\/actualidad\/wp-json\/wp\/v2\/posts\/6788\/revisions\/6795"}],"wp:attachment":[{"href":"https:\/\/www.dos30.com\/actualidad\/wp-json\/wp\/v2\/media?parent=6788"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dos30.com\/actualidad\/wp-json\/wp\/v2\/categories?post=6788"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dos30.com\/actualidad\/wp-json\/wp\/v2\/tags?post=6788"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}