{"id":6893,"date":"2022-02-16T08:50:57","date_gmt":"2022-02-16T07:50:57","guid":{"rendered":"https:\/\/www.dos30.com\/actualidad\/?p=6893"},"modified":"2022-02-16T08:50:57","modified_gmt":"2022-02-16T07:50:57","slug":"audiencias-15-febrero-2022","status":"publish","type":"post","link":"https:\/\/www.dos30.com\/actualidad\/2022\/02\/16\/audiencias-15-febrero-2022\/","title":{"rendered":"AUDIENCIAS 15 FEBRERO 2022"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">&#8216;Entrev\u00edas&#8217; (16.8%) vuelve a liderar la noche del martes y Antena 3 (15%) fue l\u00edder del d\u00eda<\/h2>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2022\/02\/1.NACIONAL-9.jpg\" alt=\"\" class=\"wp-image-6895\" width=\"837\" height=\"474\" srcset=\"https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2022\/02\/1.NACIONAL-9.jpg 721w, https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2022\/02\/1.NACIONAL-9-300x170.jpg 300w\" sizes=\"auto, (max-width: 837px) 100vw, 837px\" \/><\/figure>\n\n\n\n<p><strong>Entrev\u00edas <\/strong>L\u00cdDER de nuevo con el 16.8% de share y m\u00e1s de 1.8 millones de espectadores en pleno prime time. La serie protagonizada por Jos\u00e9 Coronado alcanz\u00f3 los m\u00e1s de 3.7 millones de contactos y se situ\u00f3 en un +18.4% por encima de la media de Telecinco.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><strong>Infiel <\/strong>se mantiene conquistando al 11.2% de cuota, 1.058.000 espectadores y 32.7% de fidelidad en la noche de Antena 3.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Bien por <strong>Sequ\u00eda <\/strong>al promediar ayer un 6.1% de share y 689.000 espectadores de media. La serie de La1 super\u00f3 ayer los 3.1 millones de contactos acumulados y fideliza al 34.3% de los mismos.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><strong>The good doctor <\/strong>fue visto por 652.000 espectadores, alcanzando un 5.2% de share en la noche de Cuatro. La serie sum\u00f3 m\u00e1s de 1.6 millones de contactos y super\u00f3 en un +14.3% la media de la cadena.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2022\/02\/2.MINUTO-DE-ORO-9.jpg\" alt=\"\" class=\"wp-image-6896\" width=\"840\" height=\"235\" srcset=\"https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2022\/02\/2.MINUTO-DE-ORO-9.jpg 593w, https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2022\/02\/2.MINUTO-DE-ORO-9-300x84.jpg 300w\" sizes=\"auto, (max-width: 840px) 100vw, 840px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2022\/02\/3.SPOT-DE-ORO-9.jpg\" alt=\"\" class=\"wp-image-6897\" width=\"840\" height=\"228\" srcset=\"https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2022\/02\/3.SPOT-DE-ORO-9.jpg 705w, https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2022\/02\/3.SPOT-DE-ORO-9-300x81.jpg 300w\" sizes=\"auto, (max-width: 840px) 100vw, 840px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2022\/02\/4.FORTA_-9.jpg\" alt=\"\" class=\"wp-image-6898\" width=\"843\" height=\"512\" srcset=\"https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2022\/02\/4.FORTA_-9.jpg 673w, https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2022\/02\/4.FORTA_-9-300x182.jpg 300w\" sizes=\"auto, (max-width: 843px) 100vw, 843px\" \/><\/figure>\n\n\n\n<p><strong>Noveleros <\/strong>contin\u00faan por encima de la cuota de TVCAN al firmar un 8.5% de cuota y 53.000 espectadores. Gusta y mucho al promediar un 55.6% de fidelidad.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Buenos datos para el prime de 8TV en el d\u00eda de ayer: El 2\u00ba d\u00eda de emisi\u00f3n de <strong>T\u00fa s\u00ed, t\u00fa no <\/strong>sube al 1% de cuota, 25.000 espectadores y 28.8% de fidelidad. Y <strong>El Circ <\/strong>consigue su 3er mejor dato de 2022 con un 2.4% de cuota y 40.000 espectadores<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>No falla ni un solo d\u00eda <strong>Qu\u00e9date Conmigo<\/strong> en la ma\u00f1ana de La7 con un 17.9% de cuota y 17.000 espectadores. Lo m\u00e1s visto del canal de nuevo <strong>7N Noticias1<\/strong> con un 13.7% y 39.000 espectadores.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>IM-PRESIONANTE <strong>Quen anda ai?<\/strong> en la tarde de TVG con un 14% de cuota, 85.000 espectadores y 36.7% de fidelidad. Un +16.6% que la cuota del canal. \u00a1L\u00cdDER DE SU FRANJA!<\/p>\n\n\n\n<p><\/p>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2022\/02\/5.PAGO_-9.jpg\" alt=\"\" class=\"wp-image-6899\" width=\"843\" height=\"515\" srcset=\"https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2022\/02\/5.PAGO_-9.jpg 669w, https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2022\/02\/5.PAGO_-9-300x183.jpg 300w\" sizes=\"auto, (max-width: 843px) 100vw, 843px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>&#8216;Entrev\u00edas&#8217; (16.8%) vuelve a liderar la noche del martes y Antena 3 (15%) fue l\u00edder del d\u00eda Entrev\u00edas L\u00cdDER de nuevo con el 16.8% de share y m\u00e1s de 1.8 millones de espectadores en pleno prime time. La serie protagonizada por Jos\u00e9 Coronado alcanz\u00f3 los m\u00e1s de 3.7 millones de contactos y se situ\u00f3 en &hellip; <a href=\"https:\/\/www.dos30.com\/actualidad\/2022\/02\/16\/audiencias-15-febrero-2022\/\" class=\"more-link\">Sigue leyendo <span class=\"screen-reader-text\">AUDIENCIAS 15 FEBRERO 2022<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[24],"tags":[],"class_list":["post-6893","post","type-post","status-publish","format-standard","hentry","category-audiencias-diarias"],"_links":{"self":[{"href":"https:\/\/www.dos30.com\/actualidad\/wp-json\/wp\/v2\/posts\/6893","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dos30.com\/actualidad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dos30.com\/actualidad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.dos30.com\/actualidad\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dos30.com\/actualidad\/wp-json\/wp\/v2\/comments?post=6893"}],"version-history":[{"count":1,"href":"https:\/\/www.dos30.com\/actualidad\/wp-json\/wp\/v2\/posts\/6893\/revisions"}],"predecessor-version":[{"id":6900,"href":"https:\/\/www.dos30.com\/actualidad\/wp-json\/wp\/v2\/posts\/6893\/revisions\/6900"}],"wp:attachment":[{"href":"https:\/\/www.dos30.com\/actualidad\/wp-json\/wp\/v2\/media?parent=6893"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dos30.com\/actualidad\/wp-json\/wp\/v2\/categories?post=6893"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dos30.com\/actualidad\/wp-json\/wp\/v2\/tags?post=6893"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}