{"id":6919,"date":"2022-02-19T12:55:41","date_gmt":"2022-02-19T11:55:41","guid":{"rendered":"https:\/\/www.dos30.com\/actualidad\/?p=6919"},"modified":"2022-02-19T13:06:25","modified_gmt":"2022-02-19T12:06:25","slug":"audiencias-18-febrero-2022","status":"publish","type":"post","link":"https:\/\/www.dos30.com\/actualidad\/2022\/02\/19\/audiencias-18-febrero-2022\/","title":{"rendered":"AUDIENCIAS 18 FEBRERO 2022"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\"><\/h2>\n\n\n\n<p><strong>Antena 3<\/strong> (16.8%) L\u00edder del viernes y <strong>\u00abMONTEALTO: REGRESO A LA CASA\u00bb<\/strong> consigue un 18.2% de cuota en el prime time de Telecinco.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2022\/02\/TOP5CADENAS.jpg\" alt=\"\" class=\"wp-image-6921\" width=\"841\" height=\"476\" srcset=\"https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2022\/02\/TOP5CADENAS.jpg 721w, https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2022\/02\/TOP5CADENAS-300x170.jpg 300w\" sizes=\"auto, (max-width: 841px) 100vw, 841px\" \/><\/figure>\n\n\n\n<p>2\u00ba mejor dato para <strong>\u00abMONTEALTO\u00bb<\/strong> en el prime time de Telecinco.  Consigue un 18.2% de share y roza los 6 millones de contactos as\u00ed como un 20% en el target de los anunciantes.<\/p>\n\n\n\n<p>Grande <strong>\u00abTU CARE ME SUENA\u00bb<\/strong> con un 20% de share, 39.7% de fidelidad y mejorando la media del canal en m\u00e1s de un +21%. Es el 2\u00ba espacio de entretenimiento m\u00e1s visto del viernes.<\/p>\n\n\n\n<p>Muy buenos datos para <strong>\u00abCUATRO AL DIA\u00bb<\/strong> en la tarde del 2\u00ba canal de Mediaset.  6.6% de share y mejorando la media de Cuatro en un +41%.  Iguala su dato del jueves y es el d\u00eda de la semana que m\u00e1s aporta (19%) a la audiencia diaria del canal.<\/p>\n\n\n\n<p>R\u00e9cord hist\u00f3rico para <strong>\u00abLAS CLAVES\u00bb<\/strong> el el Prime Time de La1.  Anota un 5.7% de share y rozando el 21% de fidelidad, siendo \u00e9ste \u00faltimo tambi\u00e9n su r\u00e9cord.<\/p>\n\n\n\n<p><strong>\u00abEL PROGRAMA DE AR\u00bb<\/strong> cierra la semana con un 20.2% de share y +32% de plusval\u00edas sobre Telecinco. L\u00cdDER INDISCUTIBLE una semana m\u00e1s, promediando un 20.6% de share y rozando los 3 millones de contactos diarios.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2022\/02\/MINUTODEORO-1.jpg\" alt=\"\" class=\"wp-image-6922\" width=\"840\" height=\"227\" srcset=\"https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2022\/02\/MINUTODEORO-1.jpg 615w, https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2022\/02\/MINUTODEORO-1-300x81.jpg 300w\" sizes=\"auto, (max-width: 840px) 100vw, 840px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2022\/02\/SPOTDEORO-1.jpg\" alt=\"\" class=\"wp-image-6923\" width=\"839\" height=\"211\" srcset=\"https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2022\/02\/SPOTDEORO-1.jpg 759w, https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2022\/02\/SPOTDEORO-1-300x75.jpg 300w\" sizes=\"auto, (max-width: 839px) 100vw, 839px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2022\/02\/TOP5AUTONOMICAS.jpg\" alt=\"\" class=\"wp-image-6924\" width=\"841\" height=\"512\" srcset=\"https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2022\/02\/TOP5AUTONOMICAS.jpg 672w, https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2022\/02\/TOP5AUTONOMICAS-300x183.jpg 300w\" sizes=\"auto, (max-width: 841px) 100vw, 841px\" \/><\/figure>\n\n\n\n<p>Muy bien por el especial en Prime Time de <strong>\u00abHASTA LA COCINA\u00bb<\/strong>. R\u00c9CORD HIST\u00d3RICO, con un 4.7% de share y rozando los 300.000 contactos.  Mejora la media de Telemadrid en m\u00e1s de un +20%.<\/p>\n\n\n\n<p>OJITO con <strong>\u00abCUINES\u00bb<\/strong>,  que ayer es el espacio con mejor share de toda FORTA.  22.7% y mejorando en un +61% la cuota total d\u00eda de TV3.<\/p>\n\n\n\n<p>R\u00c9CORD ANUAL para <strong>\u00ab120 MINUTOS\u00bb<\/strong> en las ma\u00f1anas de Telemadrid. Ayer marca un 15.1% de share, supone cerca del 20% de la audiencia del canal y TRIPLICA la cuota diaria de la cadena.<\/p>\n\n\n\n<p>Tremendos los datos d\u00eda si y d\u00eda tambi\u00e9n del magazine matinal de La7 TV <strong>\u00abQUEDATE CONMIGO\u00bb<\/strong>. Roza el 14% de share, triplicando pr\u00e1cticamente la gran cuota diaria del canal (5.3%).<\/p>\n\n\n\n<p><strong>\u00abEL CAMPO\u00bb<\/strong> marca un 16.4% de share y con plusval\u00edas del +51.1% sobre Arag\u00f3n TV. Es el 4\u00ba programa con mejor share de toda Forta.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2022\/02\/TOP5PAGO.jpg\" alt=\"\" class=\"wp-image-6925\" width=\"841\" height=\"514\" srcset=\"https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2022\/02\/TOP5PAGO.jpg 669w, https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2022\/02\/TOP5PAGO-300x183.jpg 300w\" sizes=\"auto, (max-width: 841px) 100vw, 841px\" \/><\/figure>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Antena 3 (16.8%) L\u00edder del viernes y \u00abMONTEALTO: REGRESO A LA CASA\u00bb consigue un 18.2% de cuota en el prime time de Telecinco. 2\u00ba mejor dato para \u00abMONTEALTO\u00bb en el prime time de Telecinco. Consigue un 18.2% de share y roza los 6 millones de contactos as\u00ed como un 20% en el target de los &hellip; <a href=\"https:\/\/www.dos30.com\/actualidad\/2022\/02\/19\/audiencias-18-febrero-2022\/\" class=\"more-link\">Sigue leyendo <span class=\"screen-reader-text\">AUDIENCIAS 18 FEBRERO 2022<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[24],"tags":[],"class_list":["post-6919","post","type-post","status-publish","format-standard","hentry","category-audiencias-diarias"],"_links":{"self":[{"href":"https:\/\/www.dos30.com\/actualidad\/wp-json\/wp\/v2\/posts\/6919","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dos30.com\/actualidad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dos30.com\/actualidad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.dos30.com\/actualidad\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dos30.com\/actualidad\/wp-json\/wp\/v2\/comments?post=6919"}],"version-history":[{"count":3,"href":"https:\/\/www.dos30.com\/actualidad\/wp-json\/wp\/v2\/posts\/6919\/revisions"}],"predecessor-version":[{"id":6928,"href":"https:\/\/www.dos30.com\/actualidad\/wp-json\/wp\/v2\/posts\/6919\/revisions\/6928"}],"wp:attachment":[{"href":"https:\/\/www.dos30.com\/actualidad\/wp-json\/wp\/v2\/media?parent=6919"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dos30.com\/actualidad\/wp-json\/wp\/v2\/categories?post=6919"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dos30.com\/actualidad\/wp-json\/wp\/v2\/tags?post=6919"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}