{"id":7198,"date":"2022-03-19T10:03:08","date_gmt":"2022-03-19T09:03:08","guid":{"rendered":"https:\/\/www.dos30.com\/actualidad\/?p=7198"},"modified":"2022-03-19T10:03:08","modified_gmt":"2022-03-19T09:03:08","slug":"audiencias-18-marzo-2022","status":"publish","type":"post","link":"https:\/\/www.dos30.com\/actualidad\/2022\/03\/19\/audiencias-18-marzo-2022\/","title":{"rendered":"AUDIENCIAS 18 MARZO 2022"},"content":{"rendered":"\n<p><strong>Antena 3 se hace con el d\u00eda (15.3%) gracias a una parrilla muy fuerte y consolidada en todas sus franjas.<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2022\/03\/NACIONAL.jpg\" alt=\"\" class=\"wp-image-7204\" width=\"839\" height=\"433\" srcset=\"https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2022\/03\/NACIONAL.jpg 746w, https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2022\/03\/NACIONAL-300x155.jpg 300w\" sizes=\"auto, (max-width: 839px) 100vw, 839px\" \/><\/figure>\n\n\n\n<p>Grande el equipo de EL DESAF\u00cdO al conquistar ayer al 17.3% de la audiencia en el prime time de Antena 3. EL DESAF\u00cdO lleg\u00f3 a los 2.1 millones de espectadores, 5.7 millones de contactos y mejora en un +13% la media de A3 en el d\u00eda.<\/p>\n\n\n\n<p>Anoche VIERNES DELUXE reuni\u00f3 a un total de 1.165.000 espectadores frente al televisor y alcanz\u00f3 el 12.5% de share. M\u00e1s de 5.5 millones de espectadores contactan anoche con DELUXE que aporta m\u00e1s de 1\/4 al dato diario de T5.<\/p>\n\n\n\n<p>Anoche EN EL PUNTO DE MIRA reuni\u00f3 a casi medio mill\u00f3n de espectadores en Cuatro y alcanz\u00f3 el 4.6% de share. 2.9 millones de espectadores contactan anoche con el programa situ\u00e1ndose como el 2\u00ba espacio de mayor aportaci\u00f3n a Cuatro.<\/p>\n\n\n\n<p>El programa de estreno de EQUIPO DE INVESTIGACI\u00d3N se qued\u00f3 anoche en el 5.1% de share y conquist\u00f3 a m\u00e1s de 700.000 espectadores frente a la pantalla. Super\u00f3 los 3 millones de contactos y logra una fidelidad del 23.3%.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2022\/03\/MINUTO-DE-ORO.jpg\" alt=\"\" class=\"wp-image-7200\" width=\"837\" height=\"218\" srcset=\"https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2022\/03\/MINUTO-DE-ORO.jpg 791w, https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2022\/03\/MINUTO-DE-ORO-300x78.jpg 300w, https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2022\/03\/MINUTO-DE-ORO-768x200.jpg 768w\" sizes=\"auto, (max-width: 837px) 100vw, 837px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"976\" height=\"238\" src=\"https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2022\/03\/SPOT-ORO.jpg\" alt=\"\" class=\"wp-image-7201\" srcset=\"https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2022\/03\/SPOT-ORO.jpg 976w, https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2022\/03\/SPOT-ORO-300x73.jpg 300w, https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2022\/03\/SPOT-ORO-768x187.jpg 768w\" sizes=\"auto, (max-width: 976px) 100vw, 976px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2022\/03\/FORTA.jpg\" alt=\"\" class=\"wp-image-7202\" width=\"836\" height=\"463\" srcset=\"https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2022\/03\/FORTA.jpg 694w, https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2022\/03\/FORTA-300x166.jpg 300w\" sizes=\"auto, (max-width: 836px) 100vw, 836px\" \/><\/figure>\n\n\n\n<p>Gran 16.6% de share para EUF\u00d2RIA en pleno prime time de la catalana TV3. El talent fue seguido por casi 300.000 espectadores, roza los 800.000 contactos y supera en un +6.9% la media de TV3 en el d\u00eda.<\/p>\n\n\n\n<p>Ayer EL SHOW DE BERT\u00cdN firm\u00f3 un 9.6% de cuota en el prime time de Canal Sur y alcanz\u00f3 los 200.000 espectadores. El programa conducido por Bert\u00edn Osborne supera en un +7.3% la media de la cadena andaluza en el d\u00eda.<\/p>\n\n\n\n<p>No falla nunca LUAR en la noche de los viernes y ayer se hace con el 11.1% de la audiencia gallega. El programa de TVG lleg\u00f3 a los 72.000 espectadores y casi 300.000 contactos acumulados.<\/p>\n\n\n\n<p>Est\u00e1 m\u00e1s que confirmado que 120 MINUTOS es el pilar fundamental del dato diario de Telemadrid. Ayer el magazine se marc\u00f3 un 11.6% de share en la ma\u00f1ana y congreg\u00f3 a 61.000 madrile\u00f1os frente al televisor. +157% de plusval\u00edas frente al canal.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2022\/03\/PAGO.jpg\" alt=\"\" class=\"wp-image-7203\" width=\"835\" height=\"463\" srcset=\"https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2022\/03\/PAGO.jpg 693w, https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2022\/03\/PAGO-300x166.jpg 300w\" sizes=\"auto, (max-width: 835px) 100vw, 835px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Antena 3 se hace con el d\u00eda (15.3%) gracias a una parrilla muy fuerte y consolidada en todas sus franjas. Grande el equipo de EL DESAF\u00cdO al conquistar ayer al 17.3% de la audiencia en el prime time de Antena 3. EL DESAF\u00cdO lleg\u00f3 a los 2.1 millones de espectadores, 5.7 millones de contactos y &hellip; <a href=\"https:\/\/www.dos30.com\/actualidad\/2022\/03\/19\/audiencias-18-marzo-2022\/\" class=\"more-link\">Sigue leyendo <span class=\"screen-reader-text\">AUDIENCIAS 18 MARZO 2022<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[24],"tags":[],"class_list":["post-7198","post","type-post","status-publish","format-standard","hentry","category-audiencias-diarias"],"_links":{"self":[{"href":"https:\/\/www.dos30.com\/actualidad\/wp-json\/wp\/v2\/posts\/7198","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dos30.com\/actualidad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dos30.com\/actualidad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.dos30.com\/actualidad\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dos30.com\/actualidad\/wp-json\/wp\/v2\/comments?post=7198"}],"version-history":[{"count":1,"href":"https:\/\/www.dos30.com\/actualidad\/wp-json\/wp\/v2\/posts\/7198\/revisions"}],"predecessor-version":[{"id":7205,"href":"https:\/\/www.dos30.com\/actualidad\/wp-json\/wp\/v2\/posts\/7198\/revisions\/7205"}],"wp:attachment":[{"href":"https:\/\/www.dos30.com\/actualidad\/wp-json\/wp\/v2\/media?parent=7198"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dos30.com\/actualidad\/wp-json\/wp\/v2\/categories?post=7198"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dos30.com\/actualidad\/wp-json\/wp\/v2\/tags?post=7198"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}