{"id":7273,"date":"2022-03-28T07:28:07","date_gmt":"2022-03-28T06:28:07","guid":{"rendered":"https:\/\/www.dos30.com\/actualidad\/?p=7273"},"modified":"2022-03-28T07:28:07","modified_gmt":"2022-03-28T06:28:07","slug":"audiencias-26-marzo-2022","status":"publish","type":"post","link":"https:\/\/www.dos30.com\/actualidad\/2022\/03\/28\/audiencias-26-marzo-2022\/","title":{"rendered":"AUDIENCIAS 26 MARZO 2022"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">El amistoso Espa\u00f1a-Albania es lo m\u00e1s visto del s\u00e1bado y convierte en l\u00edder del d\u00eda a La1<\/h2>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2022\/03\/1.NACIONAL-20.jpg\" alt=\"\" class=\"wp-image-7275\" width=\"843\" height=\"435\" srcset=\"https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2022\/03\/1.NACIONAL-20.jpg 746w, https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2022\/03\/1.NACIONAL-20-300x155.jpg 300w\" sizes=\"auto, (max-width: 843px) 100vw, 843px\" \/><\/figure>\n\n\n\n<p>La victoria de Espa\u00f1a ante Albania fue m\u00e1s visto del s\u00e1bado con el 25.1% de share y 3.055.000 espectadores en La1. El partido amistoso mejor\u00f3 un +114.2% la media de la cadena y super\u00f3 los 6.7 millones de contactos.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><strong>laSexta Noche <\/strong>es lo 2\u00ba + competitivo de laSexta en el d\u00eda cosechando un 7% de cuota, 683.000 espectadores y llegando a los 5.336.000 contactos \u00fanicos acumulados durante su emisi\u00f3n. Supone nada m\u00e1s y nada menos que el 37% de la audiencia del canal.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Muy buena subida de <strong>Mi casa es la tuya<\/strong> con respecto a semanas anteriores al promediar un 12.6% de share y 1.5 millones de espectadores. 5.1 millones de contactos para el programa con la visita de David Broncano, que supera en un +10.6% la media de Telecinco en el d\u00eda!<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><strong>\u00bfQui\u00e9n quiere ser millonario? <\/strong>pierde por primera vez en sus 4 semanas de emisi\u00f3n el liderato de su franja al firmar un 10.8% de cuota, 1.427.000 espectadores y 37.7% de fidelidad. Su mejor dato lo obtiene en Castilla y Le\u00f3n con un 17.3%.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Noche de cine y muchas palomitas en La1 con &#8216;<strong>Loving Pablo<\/strong>&#8216;, que se marc\u00f3 un 9.5% de share en el prime time del s\u00e1bado. La pel\u00edcula fue vista por m\u00e1s de 1.2 millones de espectadores y super\u00f3 los 4.3 millones de contactos.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>+15.7% de plusval\u00edas para <strong>Socialit\u00e9<\/strong> en la ma\u00f1ana del s\u00e1bado de Telecinco. Un total de 1.139.000 espectadores siguieron el programa, que se marca un 13.2% de share y m\u00e1s de 3.1 millones de contactos. \u00a1\u00a1Larga vida a Socialit\u00e9!!<\/p>\n\n\n\n<p><\/p>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2022\/03\/2.MINUTO-DE-ORO-19.jpg\" alt=\"\" class=\"wp-image-7276\" width=\"841\" height=\"227\" srcset=\"https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2022\/03\/2.MINUTO-DE-ORO-19.jpg 763w, https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2022\/03\/2.MINUTO-DE-ORO-19-300x81.jpg 300w\" sizes=\"auto, (max-width: 841px) 100vw, 841px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"881\" height=\"238\" src=\"https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2022\/03\/3.SPOT-DE-ORO-19.jpg\" alt=\"\" class=\"wp-image-7277\" srcset=\"https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2022\/03\/3.SPOT-DE-ORO-19.jpg 881w, https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2022\/03\/3.SPOT-DE-ORO-19-300x81.jpg 300w, https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2022\/03\/3.SPOT-DE-ORO-19-768x207.jpg 768w\" sizes=\"auto, (max-width: 881px) 100vw, 881px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2022\/03\/4.FORTA_-19.jpg\" alt=\"\" class=\"wp-image-7278\" width=\"840\" height=\"465\" srcset=\"https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2022\/03\/4.FORTA_-19.jpg 694w, https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2022\/03\/4.FORTA_-19-300x166.jpg 300w\" sizes=\"auto, (max-width: 840px) 100vw, 840px\" \/><\/figure>\n\n\n\n<p>No puede empezar mejor la 6\u00aa edici\u00f3n de <strong>Tierra de Talento<\/strong> en la noche de Canal Sur al ser lo m\u00e1s visto del canal con un 10.6% de cuota, 255.000 espectadores y 838.000 contactos \u00fanicos. Su fidelidad del 30.5% lo impulsa un 29.4% por encima.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Bien por <strong>Bamboleo<\/strong> en la noche del s\u00e1bado de TVG, y os decimos por qu\u00e9: 11% de share, 64.000 espectadores, 235.000 contactos y +12.9% de plusval\u00edas. \u00a1Programa de mayor aportaci\u00f3n a TVG!<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>M\u00e1gicos los resultados de <strong>Noche de Taifas<\/strong> en el prime de TVCAN siendo lo m\u00e1s visto del canal con su mejor dato de 2022 al quedarse con el 12.6% de cuota, 72.000 espectadores y 42% de fidelidad. Dobla la cuota del canal en el d\u00eda 2\u00aa opci\u00f3n en la franja.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>A\u00fan estando en la ma\u00f1ana, <strong>\u00c0 Correr <\/strong>se convierte en uno de los espacios m\u00e1s competitivos de \u00c0 Punt, conquistando al 6.8% de cuota, 48.000 espectadores y nada m\u00e1s y nada menos que un 63% de fidelidad. Un +116.1% que la cuota del canal en el d\u00eda.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><strong>Sexual Revolution <\/strong>se convierte de nuevo en lo m\u00e1s visto de 8TV al quedarse con el 1.3% de cuota, 19.000 espectadores y ser visto en alg\u00fan momento por 99.000 personas. Comercialmente sube al 2.3%.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2022\/03\/5.PAGO_-19.jpg\" alt=\"\" class=\"wp-image-7279\" width=\"841\" height=\"466\" srcset=\"https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2022\/03\/5.PAGO_-19.jpg 693w, https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2022\/03\/5.PAGO_-19-300x166.jpg 300w\" sizes=\"auto, (max-width: 841px) 100vw, 841px\" \/><\/figure>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El amistoso Espa\u00f1a-Albania es lo m\u00e1s visto del s\u00e1bado y convierte en l\u00edder del d\u00eda a La1 La victoria de Espa\u00f1a ante Albania fue m\u00e1s visto del s\u00e1bado con el 25.1% de share y 3.055.000 espectadores en La1. El partido amistoso mejor\u00f3 un +114.2% la media de la cadena y super\u00f3 los 6.7 millones de &hellip; <a href=\"https:\/\/www.dos30.com\/actualidad\/2022\/03\/28\/audiencias-26-marzo-2022\/\" class=\"more-link\">Sigue leyendo <span class=\"screen-reader-text\">AUDIENCIAS 26 MARZO 2022<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[24],"tags":[],"class_list":["post-7273","post","type-post","status-publish","format-standard","hentry","category-audiencias-diarias"],"_links":{"self":[{"href":"https:\/\/www.dos30.com\/actualidad\/wp-json\/wp\/v2\/posts\/7273","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dos30.com\/actualidad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dos30.com\/actualidad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.dos30.com\/actualidad\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dos30.com\/actualidad\/wp-json\/wp\/v2\/comments?post=7273"}],"version-history":[{"count":1,"href":"https:\/\/www.dos30.com\/actualidad\/wp-json\/wp\/v2\/posts\/7273\/revisions"}],"predecessor-version":[{"id":7280,"href":"https:\/\/www.dos30.com\/actualidad\/wp-json\/wp\/v2\/posts\/7273\/revisions\/7280"}],"wp:attachment":[{"href":"https:\/\/www.dos30.com\/actualidad\/wp-json\/wp\/v2\/media?parent=7273"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dos30.com\/actualidad\/wp-json\/wp\/v2\/categories?post=7273"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dos30.com\/actualidad\/wp-json\/wp\/v2\/tags?post=7273"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}