{"id":7321,"date":"2022-04-01T08:43:03","date_gmt":"2022-04-01T07:43:03","guid":{"rendered":"https:\/\/www.dos30.com\/actualidad\/?p=7321"},"modified":"2022-04-01T08:43:03","modified_gmt":"2022-04-01T07:43:03","slug":"audiencias-31-marzo-2022","status":"publish","type":"post","link":"https:\/\/www.dos30.com\/actualidad\/2022\/04\/01\/audiencias-31-marzo-2022\/","title":{"rendered":"AUDIENCIAS 31 MARZO 2022"},"content":{"rendered":"\n<p><strong>Antena 3 lidera marzo y &#8216;Cu\u00e9ntame&#8217; consigue r\u00e9cord de temporada en el \u00faltimo d\u00eda del mes.<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2022\/04\/NACIONAL.jpg\" alt=\"\" class=\"wp-image-7324\" width=\"839\" height=\"433\" srcset=\"https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2022\/04\/NACIONAL.jpg 746w, https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2022\/04\/NACIONAL-300x155.jpg 300w\" sizes=\"auto, (max-width: 839px) 100vw, 839px\" \/><\/figure>\n\n\n\n<p>R\u00e9cord de temporada para CU\u00c9NTAME C\u00d3MO PAS\u00d3 al reunir ayer a 1.390.000 espectadores en el prime time de La1. La serie firm\u00f3 un sobresaliente 10.3% de share, roz\u00f3 el 50% de fidelidad y supera en m\u00e1s de un 23% la media de La1 en el d\u00eda.<\/p>\n\n\n\n<p>ENCUENTROS INESPERADOS en el prime de La Sexta se queda esta semana con el 4.3% de cuota, 590.000 espectadores y es visto en alg\u00fan momento por 2.484.000 contactos \u00fanicos.<\/p>\n\n\n\n<p>Super dato para HORIZONTE en el prime time de Cuatro al registrar un 9% de share y 822.000 espectadores. El programa supera los 3.1 millones de contactos, +51% de plusval\u00edas respecto al canal y aporta el 24% al dato de Cuatro en el d\u00eda.<\/p>\n\n\n\n<p>12% de share para la semifinal de SECRET STORY en pleno prime time de T5 y 1.2 millones de espectadores de media. M\u00e1s de 4 millones de espectadores conectan anoche con el reality que se convierte en el programa de mayor aportaci\u00f3n a T5.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2022\/04\/MINUTO-ORO.jpg\" alt=\"\" class=\"wp-image-7325\" width=\"837\" height=\"218\" srcset=\"https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2022\/04\/MINUTO-ORO.jpg 791w, https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2022\/04\/MINUTO-ORO-300x78.jpg 300w, https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2022\/04\/MINUTO-ORO-768x200.jpg 768w\" sizes=\"auto, (max-width: 837px) 100vw, 837px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"976\" height=\"238\" src=\"https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2022\/04\/SPOT-ORO.jpg\" alt=\"\" class=\"wp-image-7326\" srcset=\"https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2022\/04\/SPOT-ORO.jpg 976w, https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2022\/04\/SPOT-ORO-300x73.jpg 300w, https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2022\/04\/SPOT-ORO-768x187.jpg 768w\" sizes=\"auto, (max-width: 976px) 100vw, 976px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2022\/04\/FORTA.jpg\" alt=\"\" class=\"wp-image-7327\" width=\"837\" height=\"463\" srcset=\"https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2022\/04\/FORTA.jpg 694w, https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2022\/04\/FORTA-300x166.jpg 300w\" sizes=\"auto, (max-width: 837px) 100vw, 837px\" \/><\/figure>\n\n\n\n<p>POL\u00d2NIA no falla a su audiencia fiel siendo de nuevo l\u00edder y el contenido no informativo m\u00e1s visto de TV3 con un 19.4%, 450.000 espectadores y 63.9% de fidelidad. Mejora en un 23.6% la cuota del canal.<\/p>\n\n\n\n<p>10 MOMENTOS firm\u00f3 ayer un 3.4% de share en el prime time de Telemadrid y reuni\u00f3 a una media de 57.000 madrile\u00f1os. El programa supera los 210.000 contactos y aporta el 7% al dato de Telemadrid en el d\u00eda.<\/p>\n\n\n\n<p>XINO XANO repite como el contenido no informativo m\u00e1s visto de \u00c0 Punt con un 2.6% de cuota, 44.000 espectadores de audiencia media y 32.9% de fidelidad. +11.3% que la cuota del canal en el d\u00eda.<\/p>\n\n\n\n<p>Es grande lo que consigue todos los jueves el equipo de LAND ROBER en el prime time gallego. Ayer se marc\u00f3 un extraordinario 18.4% de share, 130.000 espectadores y supera en un +65.1% la media de TVG. <\/p>\n\n\n\n<p>Ayer EN JAKE se marc\u00f3 un sensacional 12.7% de share en la ma\u00f1ana de ETB2 superando en un +66.1% la media de la cadena en el d\u00eda. Muy buenos datos para el magaz\u00edn vasco.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2022\/04\/PAGO.jpg\" alt=\"\" class=\"wp-image-7328\" width=\"836\" height=\"463\" srcset=\"https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2022\/04\/PAGO.jpg 693w, https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2022\/04\/PAGO-300x166.jpg 300w\" sizes=\"auto, (max-width: 836px) 100vw, 836px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Antena 3 lidera marzo y &#8216;Cu\u00e9ntame&#8217; consigue r\u00e9cord de temporada en el \u00faltimo d\u00eda del mes. R\u00e9cord de temporada para CU\u00c9NTAME C\u00d3MO PAS\u00d3 al reunir ayer a 1.390.000 espectadores en el prime time de La1. La serie firm\u00f3 un sobresaliente 10.3% de share, roz\u00f3 el 50% de fidelidad y supera en m\u00e1s de un 23% &hellip; <a href=\"https:\/\/www.dos30.com\/actualidad\/2022\/04\/01\/audiencias-31-marzo-2022\/\" class=\"more-link\">Sigue leyendo <span class=\"screen-reader-text\">AUDIENCIAS 31 MARZO 2022<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[24],"tags":[],"class_list":["post-7321","post","type-post","status-publish","format-standard","hentry","category-audiencias-diarias"],"_links":{"self":[{"href":"https:\/\/www.dos30.com\/actualidad\/wp-json\/wp\/v2\/posts\/7321","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dos30.com\/actualidad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dos30.com\/actualidad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.dos30.com\/actualidad\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dos30.com\/actualidad\/wp-json\/wp\/v2\/comments?post=7321"}],"version-history":[{"count":1,"href":"https:\/\/www.dos30.com\/actualidad\/wp-json\/wp\/v2\/posts\/7321\/revisions"}],"predecessor-version":[{"id":7329,"href":"https:\/\/www.dos30.com\/actualidad\/wp-json\/wp\/v2\/posts\/7321\/revisions\/7329"}],"wp:attachment":[{"href":"https:\/\/www.dos30.com\/actualidad\/wp-json\/wp\/v2\/media?parent=7321"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dos30.com\/actualidad\/wp-json\/wp\/v2\/categories?post=7321"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dos30.com\/actualidad\/wp-json\/wp\/v2\/tags?post=7321"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}