{"id":7408,"date":"2022-04-10T11:18:40","date_gmt":"2022-04-10T10:18:40","guid":{"rendered":"https:\/\/www.dos30.com\/actualidad\/?p=7408"},"modified":"2022-04-10T11:19:31","modified_gmt":"2022-04-10T10:19:31","slug":"audiencias-9-abril-2022","status":"publish","type":"post","link":"https:\/\/www.dos30.com\/actualidad\/2022\/04\/10\/audiencias-9-abril-2022\/","title":{"rendered":"AUDIENCIAS 9 ABRIL 2022"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">Telecinco y Antena 3 empatan en el d\u00eda con 11.1% de share. &#8216;Mi casa es la tuya&#8217; (10.2%) lidera el prime time.<\/h2>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"969\" height=\"529\" src=\"https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2022\/04\/1-2.png\" alt=\"\" class=\"wp-image-7409\" srcset=\"https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2022\/04\/1-2.png 969w, https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2022\/04\/1-2-300x164.png 300w, https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2022\/04\/1-2-768x419.png 768w\" sizes=\"auto, (max-width: 969px) 100vw, 969px\" \/><\/figure>\n\n\n\n<p><strong>Antena 3 Noticias Fin de semana 1<\/strong>, con Mat\u00edas Prats y M\u00f3nica Carrillo, es LO + VISTO del d\u00eda congregando a 1.986.000 espectadores con un 19% de share en Antena 3.<\/p>\n\n\n\n<p>M\u00e1s de 4.6 millones de espectadores conectan en alg\u00fan momento con <strong>Mi casa es la tuya<\/strong>. Firma un 10.2% de share y 1.234.000 espectadores en Telecinco. L\u00edder de su franja.<\/p>\n\n\n\n<p><strong>\u00bfQui\u00e9n quiere ser millonario?<\/strong> registra un 9.7% de share y 1.240.000 espectadores en el prime time de Antena 3. M\u00e1s de 3.8 millones de espectadores conectan en alg\u00fan momento. Registra una fidelidad del 32.1%.<\/p>\n\n\n\n<p><strong>laSexta Noche<\/strong> sigue en buena forma registrando un buen 7.2% de share y 669.000 espectadores. Destaca en hombres (8% de share) y mayores de 65 a\u00f1os (9%). M\u00e1s de 5.4 millones de contactos durante el programa.<\/p>\n\n\n\n<p><strong>Viva la vida<\/strong> firma su mejor dato desde el 12 de marzo con un 13.4% de share y 1.262.000 espectadores en la tarde de Telecinco. L\u00edder de su franja.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"791\" height=\"206\" src=\"https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2022\/04\/4-2.png\" alt=\"\" class=\"wp-image-7410\" srcset=\"https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2022\/04\/4-2.png 791w, https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2022\/04\/4-2-300x78.png 300w, https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2022\/04\/4-2-768x200.png 768w\" sizes=\"auto, (max-width: 791px) 100vw, 791px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"976\" height=\"238\" src=\"https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2022\/04\/5-2.png\" alt=\"\" class=\"wp-image-7411\" srcset=\"https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2022\/04\/5-2.png 976w, https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2022\/04\/5-2-300x73.png 300w, https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2022\/04\/5-2-768x187.png 768w\" sizes=\"auto, (max-width: 976px) 100vw, 976px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"529\" src=\"https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2022\/04\/2-2.png\" alt=\"\" class=\"wp-image-7412\" srcset=\"https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2022\/04\/2-2.png 900w, https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2022\/04\/2-2-300x176.png 300w, https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2022\/04\/2-2-768x451.png 768w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><\/figure>\n\n\n\n<p><strong>Tierra de talento<\/strong> es el programa m\u00e1s visto de Canal Sur en el d\u00eda registrando un 9.3% de share y 215.000 espectadores. 641.000 espectadores conectan en alg\u00fan momento con el programa. Destaca en mayores de 65 a\u00f1os (22.5%).<\/p>\n\n\n\n<p><strong>FAQS: Preguntes freq\u00fcents<\/strong> se mantiene fuerte registrando un 13.2% de share y 203.000 espectadores. Aporta el 24.1% del dato de la cadena en el d\u00eda.<\/p>\n\n\n\n<p><strong>Oreg\u00f3n Television<\/strong> registra un 12.5% de share y 47.000 espectadores en Arag\u00f3n TV. Se sit\u00faa un +34.2% por encima de la media de la cadena en el d\u00eda.<\/p>\n\n\n\n<p><strong>Noche De Taifas <\/strong>en Televisi\u00f3n Canaria con un 8.9% de share y 52.000 espectadores. Tiene una alta fidelidad (46.3%) y aporta el 43.5% del dato de la cadena en el d\u00eda. L\u00edder en mayores de 65 a\u00f1os (17.8% de share).<\/p>\n\n\n\n<p><strong>A C\u00f3rrer<\/strong> en \u00c0 Punt con un 5% de share y 29.000 espectadores. L\u00edder en adultos j\u00f3venes de 25 a 44 a\u00f1os (23.5% de share). Se sit\u00faa un +60.1% por encima de la media de la cadena.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"892\" height=\"529\" src=\"https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2022\/04\/3-2.png\" alt=\"\" class=\"wp-image-7413\" srcset=\"https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2022\/04\/3-2.png 892w, https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2022\/04\/3-2-300x178.png 300w, https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2022\/04\/3-2-768x455.png 768w\" sizes=\"auto, (max-width: 892px) 100vw, 892px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Telecinco y Antena 3 empatan en el d\u00eda con 11.1% de share. &#8216;Mi casa es la tuya&#8217; (10.2%) lidera el prime time. Antena 3 Noticias Fin de semana 1, con Mat\u00edas Prats y M\u00f3nica Carrillo, es LO + VISTO del d\u00eda congregando a 1.986.000 espectadores con un 19% de share en Antena 3. M\u00e1s de &hellip; <a href=\"https:\/\/www.dos30.com\/actualidad\/2022\/04\/10\/audiencias-9-abril-2022\/\" class=\"more-link\">Sigue leyendo <span class=\"screen-reader-text\">AUDIENCIAS 9 ABRIL 2022<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[24],"tags":[],"class_list":["post-7408","post","type-post","status-publish","format-standard","hentry","category-audiencias-diarias"],"_links":{"self":[{"href":"https:\/\/www.dos30.com\/actualidad\/wp-json\/wp\/v2\/posts\/7408","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dos30.com\/actualidad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dos30.com\/actualidad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.dos30.com\/actualidad\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dos30.com\/actualidad\/wp-json\/wp\/v2\/comments?post=7408"}],"version-history":[{"count":1,"href":"https:\/\/www.dos30.com\/actualidad\/wp-json\/wp\/v2\/posts\/7408\/revisions"}],"predecessor-version":[{"id":7416,"href":"https:\/\/www.dos30.com\/actualidad\/wp-json\/wp\/v2\/posts\/7408\/revisions\/7416"}],"wp:attachment":[{"href":"https:\/\/www.dos30.com\/actualidad\/wp-json\/wp\/v2\/media?parent=7408"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dos30.com\/actualidad\/wp-json\/wp\/v2\/categories?post=7408"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dos30.com\/actualidad\/wp-json\/wp\/v2\/tags?post=7408"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}