{"id":7498,"date":"2022-04-20T07:54:15","date_gmt":"2022-04-20T06:54:15","guid":{"rendered":"https:\/\/www.dos30.com\/actualidad\/?p=7498"},"modified":"2022-04-20T10:07:55","modified_gmt":"2022-04-20T09:07:55","slug":"audiencias-19-abril-2022","status":"publish","type":"post","link":"https:\/\/www.dos30.com\/actualidad\/2022\/04\/20\/audiencias-19-abril-2022\/","title":{"rendered":"AUDIENCIAS 19 ABRIL 2022"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">&#8216;Entrev\u00edas&#8217; repite liderazgo en su franja de la noche del martes otra semana m\u00e1s <\/h2>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2022\/04\/1.NACIONAL-11.jpg\" alt=\"\" class=\"wp-image-7503\" width=\"839\" height=\"475\" srcset=\"https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2022\/04\/1.NACIONAL-11.jpg 721w, https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2022\/04\/1.NACIONAL-11-300x170.jpg 300w\" sizes=\"auto, (max-width: 839px) 100vw, 839px\" \/><\/figure>\n\n\n\n<p><strong>Entrev\u00edas <\/strong>L\u00cdDER de su franja un martes m\u00e1s con el 15% de share y casi 1.6 millones de espectadores en pleno prime time. La serie super\u00f3 en un +20.8% la media de T5 en el d\u00eda, registr\u00f3 un 46.9% de fidelidad y m\u00e1s de 3.3 millones de contactos<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Un 10% redondo de cuota logr\u00f3 ayer <strong>Maestros de la Costura <\/strong>en la semifinal. Un total de 1.172.000 espectadores siguieron ayer el programa, que supera en un +14.1% la media de La1 en el d\u00eda. Adem\u00e1s, \u00a1programa de mayor aportaci\u00f3n a la cadena!<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>La segunda noche de la semana de <strong>Inocentes<\/strong> en el prime de Antena 3 consigue su mejor registro de las 3 \u00faltimas emisiones con un 11.1% de cuota, 1.021.000 espectadores y 39.2% de fidelidad Su dato alcanza el 17% en los mayores de 64 a\u00f1os<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><strong>Un Pa\u00eds para Re\u00edrlo <\/strong>firm\u00f3 en la noche de ayer un 2.2% de cuota e hizo reir a 282.000 espectadores. El programa super\u00f3 los 1.3 millones de contactos en La2 y firm\u00f3 un 21.3% de fidelidad. Ojo al 5.2% de share en Baleares.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Mejor dato de todo abril para <strong>Ya es Mediod\u00eda<\/strong>, que ayer logr\u00f3 un 15.1% de share y reuni\u00f3 a m\u00e1s de 1.2 millones de espectadores. El programa presentado por Sonsoles \u00d3nega mejor\u00f3 en un 22.1% la media de T5 en el d\u00eda y super\u00f3 los 3.2 millones de contactos.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2022\/04\/2.MINUTO-DE-ORO-11.jpg\" alt=\"\" class=\"wp-image-7501\" width=\"842\" height=\"236\" srcset=\"https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2022\/04\/2.MINUTO-DE-ORO-11.jpg 593w, https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2022\/04\/2.MINUTO-DE-ORO-11-300x84.jpg 300w\" sizes=\"auto, (max-width: 842px) 100vw, 842px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2022\/04\/3.SPOT-DE-ORO-11.jpg\" alt=\"\" class=\"wp-image-7502\" width=\"842\" height=\"213\" srcset=\"https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2022\/04\/3.SPOT-DE-ORO-11.jpg 756w, https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2022\/04\/3.SPOT-DE-ORO-11-300x76.jpg 300w\" sizes=\"auto, (max-width: 842px) 100vw, 842px\" \/><\/figure>\n\n\n\n<p><\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"673\" height=\"409\" src=\"https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2022\/04\/4.FORTA_-11.jpg\" alt=\"\" class=\"wp-image-7500\" srcset=\"https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2022\/04\/4.FORTA_-11.jpg 673w, https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2022\/04\/4.FORTA_-11-300x182.jpg 300w\" sizes=\"auto, (max-width: 673px) 100vw, 673px\" \/><\/figure>\n\n\n\n<p><strong>M\u00e1s o Menos <\/strong>firm\u00f3 ayer un 6.2% de cuota en el access prime time de Arag\u00f3n TV y congreg\u00f3 a 29.000 espectadores. M\u00e1s de 85.000 contactos acumulados y una fidelidad que supera el 31% en sus 100 minutos de duraci\u00f3n.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Fenomenal el equipo de <strong>En Jake<\/strong> al situarse ayer un +33.6% por encima de la media de ETB2 en el d\u00eda. El programa con Xabier Lapitz al frente roz\u00f3 el 10% de share, 19.000 espectadores de media y 78.000 contactos. Buena aportaci\u00f3n a la cadena: 8.5%.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Sabrosos los datos de <strong>Estache Bo! <\/strong>en la tarde gallega al firmar un excelente 10.6% de share y 67.000 espectadores. El programa de cocina de TVG mejora en un +10.6% la media de la cadena en el d\u00eda. \u00a1\u00a1MUY BIEN!!<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>\u00a1<strong>120 Minutos <\/strong>es todo un referente en Telemadrid! El magac\u00edn, con Mar\u00eda Rey al frente, logr\u00f3 ayer su 3er MEJOR DATO al firmar un 16.8% de share y 100.000 espectadores. M\u00e1s de 50% de fidelidad, \u00a1WOWWW!<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Nuestros amig@s de <strong>El Circ<\/strong> retoman de nuevo sus directos siendo lo m\u00e1s visto de 8TV con un 1.4% de cuota, 25.000 espectadores y llegando a los 173.000 contactos \u00fanicos acumulados.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2022\/04\/5.PAGO_-11.jpg\" alt=\"\" class=\"wp-image-7504\" width=\"840\" height=\"514\" srcset=\"https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2022\/04\/5.PAGO_-11.jpg 669w, https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2022\/04\/5.PAGO_-11-300x183.jpg 300w\" sizes=\"auto, (max-width: 840px) 100vw, 840px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>&#8216;Entrev\u00edas&#8217; repite liderazgo en su franja de la noche del martes otra semana m\u00e1s Entrev\u00edas L\u00cdDER de su franja un martes m\u00e1s con el 15% de share y casi 1.6 millones de espectadores en pleno prime time. La serie super\u00f3 en un +20.8% la media de T5 en el d\u00eda, registr\u00f3 un 46.9% de fidelidad &hellip; <a href=\"https:\/\/www.dos30.com\/actualidad\/2022\/04\/20\/audiencias-19-abril-2022\/\" class=\"more-link\">Sigue leyendo <span class=\"screen-reader-text\">AUDIENCIAS 19 ABRIL 2022<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[24],"tags":[],"class_list":["post-7498","post","type-post","status-publish","format-standard","hentry","category-audiencias-diarias"],"_links":{"self":[{"href":"https:\/\/www.dos30.com\/actualidad\/wp-json\/wp\/v2\/posts\/7498","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dos30.com\/actualidad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dos30.com\/actualidad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.dos30.com\/actualidad\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dos30.com\/actualidad\/wp-json\/wp\/v2\/comments?post=7498"}],"version-history":[{"count":3,"href":"https:\/\/www.dos30.com\/actualidad\/wp-json\/wp\/v2\/posts\/7498\/revisions"}],"predecessor-version":[{"id":7507,"href":"https:\/\/www.dos30.com\/actualidad\/wp-json\/wp\/v2\/posts\/7498\/revisions\/7507"}],"wp:attachment":[{"href":"https:\/\/www.dos30.com\/actualidad\/wp-json\/wp\/v2\/media?parent=7498"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dos30.com\/actualidad\/wp-json\/wp\/v2\/categories?post=7498"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dos30.com\/actualidad\/wp-json\/wp\/v2\/tags?post=7498"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}