{"id":7508,"date":"2022-04-21T07:56:54","date_gmt":"2022-04-21T06:56:54","guid":{"rendered":"https:\/\/www.dos30.com\/actualidad\/?p=7508"},"modified":"2022-04-21T07:56:55","modified_gmt":"2022-04-21T06:56:55","slug":"audiencias-20-abril-2022","status":"publish","type":"post","link":"https:\/\/www.dos30.com\/actualidad\/2022\/04\/21\/audiencias-20-abril-2022\/","title":{"rendered":"AUDIENCIAS 20 ABRIL 2022"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">&#8216;Alba&#8217; contin\u00faa liderando la noche de los mi\u00e9rcoles y &#8216;Planeta Calleja&#8217; se estrena en Cuatro ante m\u00e1s de 1 mill\u00f3n de espectadores<\/h2>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2022\/04\/1.NACIONAL-12.jpg\" alt=\"\" class=\"wp-image-7509\" width=\"842\" height=\"476\" srcset=\"https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2022\/04\/1.NACIONAL-12.jpg 721w, https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2022\/04\/1.NACIONAL-12-300x170.jpg 300w\" sizes=\"auto, (max-width: 842px) 100vw, 842px\" \/><\/figure>\n\n\n\n<p>La audiencia contin\u00faa pegada a <strong>Alba<\/strong> al firmar en la noche de Antena 3 su mejor dato de las \u00faltimas 3 semanas con un 12.7% de cuota, 1.579.000 espectadores y 50.3% de fidelidad. Adem\u00e1s, a\u00f1ade 83.000 espectadores en Diferido.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><strong>Planeta Calleja <\/strong>regresa al prime time de Cuatro con el 9.2% de share y mejorando en un +68.7% la media de la cadena en el d\u00eda! El programa con Jes\u00fas Calleja al frente fue visto por m\u00e1s de 1 mill\u00f3n de espectadores y sum\u00f3 m\u00e1s de 3.4 millones de contactos.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><strong>Pasi\u00f3n de Gavilanes <\/strong>promedia un 6.5% de share y 550.000 espectadores en la suma de los 3 episodios en el prime time de Telecinco. La serie supera los 2 millones de contactos acumulados y registra un 50.9% de fidelidad media.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>El estreno de la 3\u00aa temporada de <strong>Detr\u00e1s del Instante<\/strong> en La2 se hizo con el 1% de la audiencia, dato que se traduce en 105.000 espectadores. El programa dedicado a la fot\u00f3grafa catalana Nuria L\u00f3pez Torres llega al 2.6% de share en Baleares.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>La informaci\u00f3n manda en <strong>La Hora de La1 <\/strong>y sus resultados les avalan. Ayer firm\u00f3 un 8.8% de share y se sit\u00faa un +6.2% por encima de la media de La1 en el d\u00eda. El programa re\u00fane a 263.000 espectadores en sus 270 minutos de duraci\u00f3n.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2022\/04\/2.MINUTO-DE-ORO-12.jpg\" alt=\"\" class=\"wp-image-7511\" width=\"842\" height=\"236\" srcset=\"https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2022\/04\/2.MINUTO-DE-ORO-12.jpg 593w, https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2022\/04\/2.MINUTO-DE-ORO-12-300x84.jpg 300w\" sizes=\"auto, (max-width: 842px) 100vw, 842px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2022\/04\/3.SPOT-DE-ORO-12.jpg\" alt=\"\" class=\"wp-image-7512\" width=\"841\" height=\"217\" srcset=\"https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2022\/04\/3.SPOT-DE-ORO-12.jpg 740w, https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2022\/04\/3.SPOT-DE-ORO-12-300x77.jpg 300w\" sizes=\"auto, (max-width: 841px) 100vw, 841px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2022\/04\/4.FORTA_-12.jpg\" alt=\"\" class=\"wp-image-7513\" width=\"841\" height=\"511\" srcset=\"https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2022\/04\/4.FORTA_-12.jpg 673w, https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2022\/04\/4.FORTA_-12-300x182.jpg 300w\" sizes=\"auto, (max-width: 841px) 100vw, 841px\" \/><\/figure>\n\n\n\n<p><strong>A Sari\u00f1a busca pretendentes <\/strong>firm\u00f3 ayer un 7.8% de share en la noche de TVG y 49.000 espectadores de media. Abajo sus datos por provincias. En Lugo: 7.3% share; Orense: 8.7% share; Pontevedra: 7.7% share y A Coru\u00f1a: 7.8% share.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Es todo un \u00e9xito de audiencia <strong>Pera Limonera.<\/strong> El formato de Arag\u00f3n TV es un \u00e9xito asegurado en cualquiera de las franjas en las que se emita. Ayer firm\u00f3 un excelente 10% de share en la ma\u00f1ana, 8.000 espectadores y m\u00e1s del 51% de fidelidad.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Maravillosos los datos que consigue, ma\u00f1ana tras ma\u00f1ana, <strong>En Jake <\/strong>en ETB2. El magac\u00edn se hizo ayer con el 10.5% de la audiencia, resultado que se traduce en 21.000 espectadores. Ojo porque mejora en un +14.1% la media de ETB2 en el d\u00eda.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Pero qu\u00e9 grandes son los compis de <strong>120 Minutos<\/strong>, que ayer se marcaron un 8.1% de share en la ma\u00f1ana de Telemadrid. Un total de 55.000 espectadores siguieron el magac\u00edn, que supera en m\u00e1s de un 60% la media de la cadena en el d\u00eda.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Y contin\u00faan los DATAZOS de La7 con un 7.8% de cuota en el d\u00eda: <strong>El Entierro Infantil de la Sardina<\/strong> es lo m\u00e1s visto del canal con un 11.7% y 50.000 espectadores Bien tambi\u00e9n <strong>7N Noticias 1<\/strong> con un 13.9% y 39.000 espectadores.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2022\/04\/5.PAGO_-12.jpg\" alt=\"\" class=\"wp-image-7514\" width=\"843\" height=\"515\" srcset=\"https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2022\/04\/5.PAGO_-12.jpg 669w, https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2022\/04\/5.PAGO_-12-300x183.jpg 300w\" sizes=\"auto, (max-width: 843px) 100vw, 843px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>&#8216;Alba&#8217; contin\u00faa liderando la noche de los mi\u00e9rcoles y &#8216;Planeta Calleja&#8217; se estrena en Cuatro ante m\u00e1s de 1 mill\u00f3n de espectadores La audiencia contin\u00faa pegada a Alba al firmar en la noche de Antena 3 su mejor dato de las \u00faltimas 3 semanas con un 12.7% de cuota, 1.579.000 espectadores y 50.3% de fidelidad. &hellip; <a href=\"https:\/\/www.dos30.com\/actualidad\/2022\/04\/21\/audiencias-20-abril-2022\/\" class=\"more-link\">Sigue leyendo <span class=\"screen-reader-text\">AUDIENCIAS 20 ABRIL 2022<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[24],"tags":[],"class_list":["post-7508","post","type-post","status-publish","format-standard","hentry","category-audiencias-diarias"],"_links":{"self":[{"href":"https:\/\/www.dos30.com\/actualidad\/wp-json\/wp\/v2\/posts\/7508","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dos30.com\/actualidad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dos30.com\/actualidad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.dos30.com\/actualidad\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dos30.com\/actualidad\/wp-json\/wp\/v2\/comments?post=7508"}],"version-history":[{"count":1,"href":"https:\/\/www.dos30.com\/actualidad\/wp-json\/wp\/v2\/posts\/7508\/revisions"}],"predecessor-version":[{"id":7515,"href":"https:\/\/www.dos30.com\/actualidad\/wp-json\/wp\/v2\/posts\/7508\/revisions\/7515"}],"wp:attachment":[{"href":"https:\/\/www.dos30.com\/actualidad\/wp-json\/wp\/v2\/media?parent=7508"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dos30.com\/actualidad\/wp-json\/wp\/v2\/categories?post=7508"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dos30.com\/actualidad\/wp-json\/wp\/v2\/tags?post=7508"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}