{"id":7624,"date":"2022-05-03T08:03:15","date_gmt":"2022-05-03T07:03:15","guid":{"rendered":"https:\/\/www.dos30.com\/actualidad\/?p=7624"},"modified":"2022-05-03T08:09:57","modified_gmt":"2022-05-03T07:09:57","slug":"audiencias-2-mayo-2022","status":"publish","type":"post","link":"https:\/\/www.dos30.com\/actualidad\/2022\/05\/03\/audiencias-2-mayo-2022\/","title":{"rendered":"AUDIENCIAS 2 MAYO 2022"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">&#8216;MasterChef&#8217; se sit\u00faa como la primera opci\u00f3n de su franja en el prime time de La1<\/h2>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2022\/05\/1.NACIONAL-1.jpg\" alt=\"\" class=\"wp-image-7626\" width=\"835\" height=\"431\" srcset=\"https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2022\/05\/1.NACIONAL-1.jpg 746w, https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2022\/05\/1.NACIONAL-1-300x155.jpg 300w\" sizes=\"auto, (max-width: 835px) 100vw, 835px\" \/><\/figure>\n\n\n\n<p>Un 13.7% de share para <strong>MasterChef<\/strong> en la noche del lunes y 1.615.000 espectadores. El programa supera en m\u00e1s de un 53% la media de La1 en el d\u00eda y congrega a un total de 4.8 millones de contactos.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>M\u00e1s de 1.3 millones de espectadores no se perdieron anoche el estreno de <strong>Desaparecidos<\/strong> en pleno prime time de Telecinco. La serie anot\u00f3 un 12.1% de share, super\u00f3 los 3.4 millones de contactos y registr\u00f3 casi el 39% de fidelidad.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><strong>Inocentes <\/strong>comienza su semana con un 9.7% de cuota, 984.000 espectadores y 41.4% de fidelidad. \u00a1Fue la 3\u00aa opci\u00f3n en su franja! Supone el 9.5% de la audiencia del d\u00eda de Antena 3.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Noche de estreno en Cuatro con <strong>Los Miedos De<\/strong>, que fue visto por 645.000 espectadores y super\u00f3 en un +16.2% la media de la cadena en el d\u00eda. El programa firm\u00f3 un 5.6% de cuota y alcanz\u00f3 m\u00e1s de 2.9 millones de contactos.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Grandes datos para <strong>S\u00e1lvame<\/strong>, que ayer fue sin duda L\u00cdDER de su franja (15:59h-20:01h) al promediar un 14.3% de share con +2 puntos sobre su directo competidor! <strong>S\u00e1lvame Lim\u00f3n <\/strong>sube al 12.1% de share y 1.314.000 espectadores, <strong>S\u00e1lvame Naranja <\/strong>anota un gran 15% de share y 1.520.000 espectadores.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Los an\u00e1lisis de I\u00f1aki L\u00f3pez y Cristina Pardo en <strong>M\u00e1s Vale Tarde <\/strong>se quedan con el 6.2% de cuota, 625.000 espectadores y superan los 3M de contactos durante su emisi\u00f3n. Muy buenos datos en todos los targets poblacionales.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2022\/05\/2.MINUTO-DE-ORO-1.jpg\" alt=\"\" class=\"wp-image-7627\" width=\"839\" height=\"227\" srcset=\"https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2022\/05\/2.MINUTO-DE-ORO-1.jpg 763w, https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2022\/05\/2.MINUTO-DE-ORO-1-300x81.jpg 300w\" sizes=\"auto, (max-width: 839px) 100vw, 839px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"832\" height=\"238\" src=\"https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2022\/05\/3.SPOT-DE-ORO-1.jpg\" alt=\"\" class=\"wp-image-7628\" srcset=\"https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2022\/05\/3.SPOT-DE-ORO-1.jpg 832w, https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2022\/05\/3.SPOT-DE-ORO-1-300x86.jpg 300w, https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2022\/05\/3.SPOT-DE-ORO-1-768x220.jpg 768w\" sizes=\"auto, (max-width: 832px) 100vw, 832px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2022\/05\/4.FORTA_-1.jpg\" alt=\"\" class=\"wp-image-7629\" width=\"840\" height=\"465\" srcset=\"https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2022\/05\/4.FORTA_-1.jpg 694w, https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2022\/05\/4.FORTA_-1-300x166.jpg 300w\" sizes=\"auto, (max-width: 840px) 100vw, 840px\" \/><\/figure>\n\n\n\n<p>Espectacular estreno de la tercera temporada de <strong>Crims <\/strong>en el prime de TV3 con un 23% de cuota, 546.000 espectadores y 885.000 contactos. Enganchad\u00edsima la audiencia al conseguir un 61.6% de fidelidad. Un +46% que la cuota de TV3.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>La informaci\u00f3n tiene nombre y se llama <strong>En Jake.<\/strong> El programa firm\u00f3 ayer un excelente 9.5% de share en la ma\u00f1ana de ETB2, congreg\u00f3 a 18.000 espectadores y suma 78.000 contactos acumulados. \u00a1Bien por todo el equipo de En Jake!<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Muy buena subida de casi 2 puntos para <strong>Andaluc\u00eda de Fiesta<\/strong> en su 2\u00aa semana de esta nueva temporada al firmar un 7.4% de cuota, 183.000 espectadores y 29.9% de fidelidad. Recibe 98.000 contactos m\u00e1s que en el estreno en la noche de Canal Sur.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>M\u00e1ximo para <strong>Bona Vesprada<\/strong> con un 5.2% de cuota, 60.000 espectadores y 40.1% de fidelidad. En total <strong>Bona Vesprada<\/strong> de 16:08 a 19:16 horas aporta el 29.9% de la audiencia de \u00c0 Punt en el d\u00eda.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Enamorados nos tiene <strong>Gente Maravillosa<\/strong> en el prime de TVCAN, alcanzando el 9.6% de cuota, 55.000 espectadores y 45.6% de fidelidad. Un +51.5% que la cuota del canal, 20.7% de aportaci\u00f3n. Un 14.4% comercialmente hablando.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2022\/05\/5.PAGO_-1.jpg\" alt=\"\" class=\"wp-image-7630\" width=\"841\" height=\"466\" srcset=\"https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2022\/05\/5.PAGO_-1.jpg 693w, https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2022\/05\/5.PAGO_-1-300x166.jpg 300w\" sizes=\"auto, (max-width: 841px) 100vw, 841px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>&#8216;MasterChef&#8217; se sit\u00faa como la primera opci\u00f3n de su franja en el prime time de La1 Un 13.7% de share para MasterChef en la noche del lunes y 1.615.000 espectadores. El programa supera en m\u00e1s de un 53% la media de La1 en el d\u00eda y congrega a un total de 4.8 millones de contactos. &hellip; <a href=\"https:\/\/www.dos30.com\/actualidad\/2022\/05\/03\/audiencias-2-mayo-2022\/\" class=\"more-link\">Sigue leyendo <span class=\"screen-reader-text\">AUDIENCIAS 2 MAYO 2022<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[24],"tags":[],"class_list":["post-7624","post","type-post","status-publish","format-standard","hentry","category-audiencias-diarias"],"_links":{"self":[{"href":"https:\/\/www.dos30.com\/actualidad\/wp-json\/wp\/v2\/posts\/7624","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dos30.com\/actualidad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dos30.com\/actualidad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.dos30.com\/actualidad\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dos30.com\/actualidad\/wp-json\/wp\/v2\/comments?post=7624"}],"version-history":[{"count":2,"href":"https:\/\/www.dos30.com\/actualidad\/wp-json\/wp\/v2\/posts\/7624\/revisions"}],"predecessor-version":[{"id":7632,"href":"https:\/\/www.dos30.com\/actualidad\/wp-json\/wp\/v2\/posts\/7624\/revisions\/7632"}],"wp:attachment":[{"href":"https:\/\/www.dos30.com\/actualidad\/wp-json\/wp\/v2\/media?parent=7624"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dos30.com\/actualidad\/wp-json\/wp\/v2\/categories?post=7624"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dos30.com\/actualidad\/wp-json\/wp\/v2\/tags?post=7624"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}