{"id":7633,"date":"2022-05-04T08:03:15","date_gmt":"2022-05-04T07:03:15","guid":{"rendered":"https:\/\/www.dos30.com\/actualidad\/?p=7633"},"modified":"2022-05-04T08:06:06","modified_gmt":"2022-05-04T07:06:06","slug":"audiencias-3-mayo-2022","status":"publish","type":"post","link":"https:\/\/www.dos30.com\/actualidad\/2022\/05\/04\/audiencias-3-mayo-2022\/","title":{"rendered":"AUDIENCIAS 3 MAYO 2022"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">&#8216;S\u00e1lvame&#8217; brilla en la tarde de Telecinco y &#8216;Entrev\u00edas&#8217; mantiene su liderazgo en la noche de los martes una semana m\u00e1s <\/h2>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2022\/05\/1.NACIONAL-2.jpg\" alt=\"\" class=\"wp-image-7634\" width=\"838\" height=\"474\" srcset=\"https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2022\/05\/1.NACIONAL-2.jpg 721w, https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2022\/05\/1.NACIONAL-2-300x170.jpg 300w\" sizes=\"auto, (max-width: 838px) 100vw, 838px\" \/><\/figure>\n\n\n\n<p><strong>S\u00e1lvame <\/strong>L\u00cdDER indiscutible de su franja al promediar un 16.3% de share en sus 4h de duraci\u00f3n con +4 puntos sobre su directo competidor, \u00a1WOW! <strong>S\u00e1lvame Lim\u00f3n <\/strong>se eleva al 13% share y 1.358.000 espectadores y <strong>S\u00e1lvame Naranja <\/strong>logra un gran 17.5% share, 1.636.000 espectadores, \u00a1siendo su 2\u00aa MEJOR CUOTA DEL A\u00d1O!<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Otro martes m\u00e1s, <strong>Entrev\u00edas <\/strong>L\u00cdDER de su franja con el 15.5% de share y m\u00e1s de 1.7 millones de espectadores. La serie protagonizada por Jos\u00e9 Coronado super\u00f3 los 3.6 millones de contactos y mejor\u00f3 en un +11.3% la media de Telecinco en el d\u00eda.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><strong>Inocentes <\/strong>en el prime de Antena 3 se hace con el 9.5% de cuota, 930.000 espectadores y 37.2% de fidelidad. Es 2\u00aa opci\u00f3n en su franja de emisi\u00f3n.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>El ESTRENO de la 3\u00aa temporada de <strong>La Noche D<\/strong> firm\u00f3 un 7.6% de share y 873.000 espectadores. El programa logr\u00f3 un total de 3.8 millones de contactos y supera en un +2.5% la media de La1 en el d\u00eda.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Pero qu\u00e9 bien funciona <strong>Rutas Bizarras <\/strong> en el prime time de La2. M\u00c1XIMO DE TEMPORADA al registrar ayer un 2.7% de share y 419.000 espectadores. Ojo porque supera en casi un +2% la media de La2 en el d\u00eda y llega a los 1.7 millones de contactos.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>La visita de William Levy a <strong>El Hormiguero<\/strong> enamora al 16.4% de cuota, 2.510.000 espectadores y llega a los 5.728.000 contactos \u00fanicos. El programa l\u00edder de su franja con 5.7 puntos de diferencia sobre la 2\u00aa cadena.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2022\/05\/2.MINUTO-DE-ORO-2.jpg\" alt=\"\" class=\"wp-image-7635\" width=\"840\" height=\"235\" srcset=\"https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2022\/05\/2.MINUTO-DE-ORO-2.jpg 593w, https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2022\/05\/2.MINUTO-DE-ORO-2-300x84.jpg 300w\" sizes=\"auto, (max-width: 840px) 100vw, 840px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2022\/05\/3.SPOT-DE-ORO-2.jpg\" alt=\"\" class=\"wp-image-7636\" width=\"840\" height=\"248\" srcset=\"https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2022\/05\/3.SPOT-DE-ORO-2.jpg 647w, https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2022\/05\/3.SPOT-DE-ORO-2-300x89.jpg 300w\" sizes=\"auto, (max-width: 840px) 100vw, 840px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2022\/05\/4.FORTA_-2.jpg\" alt=\"\" class=\"wp-image-7637\" width=\"840\" height=\"510\" srcset=\"https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2022\/05\/4.FORTA_-2.jpg 673w, https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2022\/05\/4.FORTA_-2-300x182.jpg 300w\" sizes=\"auto, (max-width: 840px) 100vw, 840px\" \/><\/figure>\n\n\n\n<p>Muy bien <strong>Tupper Club<\/strong>, que en su 2\u00aa emisi\u00f3n en TVG registra un destacado 9% de share y atrae a 64.000 espectadores. Contin\u00faa con m\u00e1s del 40% de fidelidad y el 44.2% de los espectadores que vio el estreno, repite en su 2\u00ba programa. \u00a1\u00a1BUENOS DATOS!!<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Fenomenal <strong>Nos Echamos a la Calle<\/strong>, que en la tarde de ayer subi\u00f3 hasta el 7.3% de share y logra su 4\u00ba MEJOR DATO DEL A\u00d1O en cuota. El programa fue seguido por 30.000 espectadores y 78.000 contactos. \u00a1MAYOR FIDELIDAD del 2022, WOWWW!<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Incre\u00edble <strong>7N Noticias 1<\/strong> con su mejor cuota desde el 21 de abril con un 16.2% y 45.000 espectadores, lo m\u00e1s visto de La 7 TV en el d\u00eda. Adem\u00e1s, <strong>La Procesi\u00f3n del Ba\u00f1o de la Vera Cruz <\/strong>es visto en alg\u00fan momento por 119.000 personas \u00fanicas, con un 5.2% de cuota.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Sin palabras para lo que consigue <strong>Noveleros<\/strong> semana a semana en el prime de TVCAN! Ayer es de nuevo lo m\u00e1s visto del canal con un 10.7% de cuota, 66.000 espectadores y 52.9% de fidelidad. Un +84.3% que la cuota del canal.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Lo siguen bordando los compa\u00f1eros de <strong>120 Minutos<\/strong> al registrar ayer un excelente 9.3% de share y 54.000 espectadores de media. El magaz\u00edn matinal de Telemadrid supera en m\u00e1s de un 71% la media de la cadena en el d\u00eda! \u00a1BIEN!<\/p>\n\n\n\n<p><\/p>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2022\/05\/5.PAGO_-2.jpg\" alt=\"\" class=\"wp-image-7638\" width=\"843\" height=\"515\" srcset=\"https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2022\/05\/5.PAGO_-2.jpg 670w, https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2022\/05\/5.PAGO_-2-300x183.jpg 300w\" sizes=\"auto, (max-width: 843px) 100vw, 843px\" \/><\/figure>\n\n\n\n<p>El partidazo del <strong>Villareal CF<\/strong> en Champions arrasa como lo m\u00e1s visto del universo del Pago con un 49.3% de cuota pago, 985.000 espectadores y 51.6% de fidelidad. Lo que es raro es que su cuota sea del 45.2% en el \u00e1mbito de la C. Valenciana.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8216;S\u00e1lvame&#8217; brilla en la tarde de Telecinco y &#8216;Entrev\u00edas&#8217; mantiene su liderazgo en la noche de los martes una semana m\u00e1s S\u00e1lvame L\u00cdDER indiscutible de su franja al promediar un 16.3% de share en sus 4h de duraci\u00f3n con +4 puntos sobre su directo competidor, \u00a1WOW! S\u00e1lvame Lim\u00f3n se eleva al 13% share y 1.358.000 &hellip; <a href=\"https:\/\/www.dos30.com\/actualidad\/2022\/05\/04\/audiencias-3-mayo-2022\/\" class=\"more-link\">Sigue leyendo <span class=\"screen-reader-text\">AUDIENCIAS 3 MAYO 2022<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[24],"tags":[],"class_list":["post-7633","post","type-post","status-publish","format-standard","hentry","category-audiencias-diarias"],"_links":{"self":[{"href":"https:\/\/www.dos30.com\/actualidad\/wp-json\/wp\/v2\/posts\/7633","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dos30.com\/actualidad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dos30.com\/actualidad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.dos30.com\/actualidad\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dos30.com\/actualidad\/wp-json\/wp\/v2\/comments?post=7633"}],"version-history":[{"count":2,"href":"https:\/\/www.dos30.com\/actualidad\/wp-json\/wp\/v2\/posts\/7633\/revisions"}],"predecessor-version":[{"id":7643,"href":"https:\/\/www.dos30.com\/actualidad\/wp-json\/wp\/v2\/posts\/7633\/revisions\/7643"}],"wp:attachment":[{"href":"https:\/\/www.dos30.com\/actualidad\/wp-json\/wp\/v2\/media?parent=7633"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dos30.com\/actualidad\/wp-json\/wp\/v2\/categories?post=7633"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dos30.com\/actualidad\/wp-json\/wp\/v2\/tags?post=7633"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}