{"id":8173,"date":"2022-07-04T07:49:11","date_gmt":"2022-07-04T06:49:11","guid":{"rendered":"https:\/\/www.dos30.com\/actualidad\/?p=8173"},"modified":"2022-07-04T07:49:11","modified_gmt":"2022-07-04T06:49:11","slug":"audiencias-03-julio-2022","status":"publish","type":"post","link":"https:\/\/www.dos30.com\/actualidad\/2022\/07\/04\/audiencias-03-julio-2022\/","title":{"rendered":"AUDIENCIAS 03 JULIO 2022"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">Telecinco, l\u00edder del d\u00eda, y &#8216;Supervivientes: Conexi\u00f3n Honduras&#8217; brilla un domingo m\u00e1s en prime time <\/h2>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2022\/07\/1.NACIONAL-1.jpg\" alt=\"\" class=\"wp-image-8174\" width=\"841\" height=\"433\" srcset=\"https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2022\/07\/1.NACIONAL-1.jpg 746w, https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2022\/07\/1.NACIONAL-1-300x154.jpg 300w\" sizes=\"auto, (max-width: 841px) 100vw, 841px\" \/><\/figure>\n\n\n\n<p><strong>Supervivientes: Conexi\u00f3n Honduras <\/strong>L\u00cdDER un d\u00eda m\u00e1s, y con +2.9 puntos sobre su competidor, al lograr un 17.9% de share y reunir a 1.929.000 espectadores en prime time. La gala del domingo presentada por Ion Aramendi supera los 5.4 millones de contactos y registra +34.8% de plusval\u00edas.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Doble ficci\u00f3n en el prime time del domingo en Antena 3: <strong>Hermanos <\/strong>firma un 13.8% de share y 1.732.000 espectadores. Fidelidad del 50.9% e <strong>Infiel <\/strong>crece m\u00e1s de 1 punto, respecto al domingo pasado, registrando un 18.5% y 1.543.000 espectadores.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>&#8216;<strong>Explota explota&#8217;<\/strong> se marc\u00f3 en pleno prime time de La1 un 7.2% de share. La pel\u00edcula fue seguida por 870.000 espectadores, 4.3 millones de contactos y logra un 20.1% de fidelidad. Un 8.8% en el grupo 45-64 a\u00f1os.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><strong>Cuarto Milenio <\/strong>gusta al 6% share y 701.000 espectadores en prime time, \u00a1siendo lo m\u00e1s visto de Cuatro! El programa presentado por Iker Jim\u00e9nez roza los 3.8 millones de contactos, aporta el 23.3% al dato de Cuatro y supera en un +11.5% la media de la cadena en el d\u00eda.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Un \u00a1hurra! por <strong>Aqu\u00ed la Tierra <\/strong>por marcarse ayer un 8.3% de share y 772.000 espectadores en la tarde de La1. Con Quico Taronj\u00ed al frente, el programa mejora un +7% la media de la cadena p\u00fablica en el d\u00eda. \u00a1\u00a1Bien!!<\/p>\n\n\n\n<p><\/p>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2022\/07\/2.MINUTO-DE-ORO-1.jpg\" alt=\"\" class=\"wp-image-8175\" width=\"841\" height=\"227\" srcset=\"https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2022\/07\/2.MINUTO-DE-ORO-1.jpg 763w, https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2022\/07\/2.MINUTO-DE-ORO-1-300x81.jpg 300w\" sizes=\"auto, (max-width: 841px) 100vw, 841px\" \/><\/figure>\n\n\n\n<p><\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"875\" height=\"238\" src=\"https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2022\/07\/3.SPOT-DE-ORO-1.jpg\" alt=\"\" class=\"wp-image-8176\" srcset=\"https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2022\/07\/3.SPOT-DE-ORO-1.jpg 875w, https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2022\/07\/3.SPOT-DE-ORO-1-300x82.jpg 300w, https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2022\/07\/3.SPOT-DE-ORO-1-768x209.jpg 768w\" sizes=\"auto, (max-width: 875px) 100vw, 875px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2022\/07\/4.FORTA_-1.jpg\" alt=\"\" class=\"wp-image-8177\" width=\"841\" height=\"465\" srcset=\"https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2022\/07\/4.FORTA_-1.jpg 694w, https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2022\/07\/4.FORTA_-1-300x166.jpg 300w\" sizes=\"auto, (max-width: 841px) 100vw, 841px\" \/><\/figure>\n\n\n\n<p>En la noche del domingo los compis de <strong>Preguntes Freq\u00fcents<\/strong> se hacen con el 13.2% de la audiencia catalana. M\u00e1s de 200.000 espectadores siguieron ayer el programa, que aporta m\u00e1s del 21% al dato de TV3 en el d\u00eda.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Im-presionante 22.9% de share para la final\u00edsima de <strong>Jotalent<\/strong> en el prime time de Arag\u00f3n TV. El programa alcanz\u00f3 los 84.000 espectadores, casi duplica la media de la cadena en el d\u00eda y aporta m\u00e1s del 44% al dato del canal. \u00a1WOWWW!<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>+73.7% por encima de la media del canal se situ\u00f3 ayer <strong>En Otra Clave<\/strong>. El programa de RTVC firm\u00f3 un 6.6% de share, 37.000 espectadores, m\u00e1s de 100.000 contactos y ojo porque aporta m\u00e1s del 21% al dato de la cadena en el d\u00eda.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Ol\u00e9 por <strong>Historias a Bocados<\/strong> y la buena tele en la tarde dominical de ETB2. La visita a Sukarrieta congreg\u00f3 ayer al 6.8% de la audiencia de Euskadi, 34.000 espectadores y 134.000 contactos. \u00a1Gran fidelidad que supera el 45%!<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>5.2% de share para <strong>M\u00fasica para mis o\u00eddos<\/strong> en el prime time de Canal Sur. El programa lleg\u00f3 hasta 108.000 andaluces y andaluzas, m\u00e1s de 370.000 contactos y roza el 30% de fidelidad. En mayores de 65 a\u00f1os 9.7% de share.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Oigan pero qu\u00e9 locura los datos de <strong>Saudade de Ti<\/strong> en el prime time de TVG. La serie se marca un 10% de share, 75.000 espectadores y atenci\u00f3n porque supera en un +12.6% la media de TVG en el d\u00eda. \u00a1Chap\u00f3!<\/p>\n\n\n\n<p><\/p>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2022\/07\/5.PAGO_-1.jpg\" alt=\"\" class=\"wp-image-8178\" width=\"841\" height=\"466\" srcset=\"https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2022\/07\/5.PAGO_-1.jpg 693w, https:\/\/www.dos30.com\/actualidad\/wp-content\/uploads\/2022\/07\/5.PAGO_-1-300x166.jpg 300w\" sizes=\"auto, (max-width: 841px) 100vw, 841px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Telecinco, l\u00edder del d\u00eda, y &#8216;Supervivientes: Conexi\u00f3n Honduras&#8217; brilla un domingo m\u00e1s en prime time Supervivientes: Conexi\u00f3n Honduras L\u00cdDER un d\u00eda m\u00e1s, y con +2.9 puntos sobre su competidor, al lograr un 17.9% de share y reunir a 1.929.000 espectadores en prime time. La gala del domingo presentada por Ion Aramendi supera los 5.4 millones &hellip; <a href=\"https:\/\/www.dos30.com\/actualidad\/2022\/07\/04\/audiencias-03-julio-2022\/\" class=\"more-link\">Sigue leyendo <span class=\"screen-reader-text\">AUDIENCIAS 03 JULIO 2022<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[24],"tags":[],"class_list":["post-8173","post","type-post","status-publish","format-standard","hentry","category-audiencias-diarias"],"_links":{"self":[{"href":"https:\/\/www.dos30.com\/actualidad\/wp-json\/wp\/v2\/posts\/8173","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dos30.com\/actualidad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dos30.com\/actualidad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.dos30.com\/actualidad\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dos30.com\/actualidad\/wp-json\/wp\/v2\/comments?post=8173"}],"version-history":[{"count":1,"href":"https:\/\/www.dos30.com\/actualidad\/wp-json\/wp\/v2\/posts\/8173\/revisions"}],"predecessor-version":[{"id":8179,"href":"https:\/\/www.dos30.com\/actualidad\/wp-json\/wp\/v2\/posts\/8173\/revisions\/8179"}],"wp:attachment":[{"href":"https:\/\/www.dos30.com\/actualidad\/wp-json\/wp\/v2\/media?parent=8173"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dos30.com\/actualidad\/wp-json\/wp\/v2\/categories?post=8173"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dos30.com\/actualidad\/wp-json\/wp\/v2\/tags?post=8173"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}